{"id":6221,"date":"2025-07-18T13:41:10","date_gmt":"2025-07-18T16:41:10","guid":{"rendered":"https:\/\/wargodspress.com.br\/wargods\/?p=6221"},"modified":"2025-07-18T13:41:12","modified_gmt":"2025-07-18T16:41:12","slug":"gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/","title":{"rendered":"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final"},"content":{"rendered":"\n<p>Os estadunidenses do <strong>Silver Talon<\/strong> est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de <strong><em>\u201cDecadence and Decay\u201d<\/em><\/strong> (2021). Em fase avan\u00e7ada de produ\u00e7\u00e3o, o disco teve suas sess\u00f5es iniciadas ainda em outubro de 2024 e j\u00e1 conta com os vocais e as baterias finalizados. Segundo o guitarrista <strong>Bryce<\/strong> <strong>VanHoosen<\/strong>, neste momento a banda se concentra nas grava\u00e7\u00f5es das guitarras e do baixo \u2014 \u00faltima etapa antes da mixagem e masteriza\u00e7\u00e3o.<\/p>\n\n\n\n<p>As baterias foram registradas no <strong>Falcon<\/strong> <strong>Studios<\/strong>, em Portland, Oregon, com engenharia de som a cargo de <strong>Gabe<\/strong> <strong>Johnston<\/strong>, conhecido por seus trabalhos com <strong>Unto<\/strong> <strong>Others<\/strong>, <strong>Idle<\/strong> <strong>Hands<\/strong>, <strong>Spellcaster<\/strong> e <strong>Vintersea <\/strong>e tamb\u00e9m respons\u00e1vel pela produ\u00e7\u00e3o do debut do <strong>Silver Talon<\/strong>. Em janeiro deste ano, os f\u00e3s puderam acompanhar pr\u00e9vias dos vocais atrav\u00e9s de v\u00eddeos publicados nas redes sociais da banda, revelando o andamento das sess\u00f5es e a pot\u00eancia vocal de <strong>Wyatt<\/strong> <strong>Howell<\/strong>.<\/p>\n\n\n\n<p>Uma das primeiras faixas divulgadas ao p\u00fablico, <strong><em>\u201cIron\u201d<\/em><\/strong>, foi apresentada no canal <strong>EMGtv<\/strong>, em uma performance ao vivo de <strong>Bryce<\/strong> com sua Jackson King V, equipada com captadores EMG. O trecho mostrou a aposta da banda em um som ainda mais agressivo e t\u00e9cnico, reflexo da proposta de manter o peso e a dramaticidade do Heavy Metal tradicional, mas com arranjos progressivos e uma dose de obscuridade.<\/p>\n\n\n\n<p>De acordo com <strong>Bryce<\/strong> <strong>VanHoosen<\/strong>, o grupo busca capturar performances <em>\u201ccom mais energia e precis\u00e3o\u201d<\/em> do que no disco anterior. A expectativa \u00e9 de que o novo trabalho seja conclu\u00eddo nas pr\u00f3ximas semanas e lan\u00e7ado ainda em 2025. Enquanto finaliza o \u00e1lbum, o <strong>Silver Talon<\/strong> tamb\u00e9m se prepara para cair na estrada. Em agosto, o grupo far\u00e1 uma sequ\u00eancia de apresenta\u00e7\u00f5es pelos Estados Unidos, incluindo participa\u00e7\u00e3o no <strong>Grillfest<\/strong>, em Salt Lake City.<\/p>\n\n\n\n<p><strong>Confira a agenda:<\/strong><\/p>\n\n\n\n<p>20\/08 \u2013 Bend, OR<br>21\/08 \u2013 Richland, WA<br>22\u201323\/08 \u2013 Grillfest, Salt Lake City, UT<br>24\/08 \u2013 Reno, NV<br>25\/08 \u2013 Eureka, CA<\/p>\n\n\n\n<p><strong><em>Assista ao v\u00eddeo de \u201cIron\u201d:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bryce VanHoosen performs &quot;Iron&quot; on EMGtv\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/y41PPfXEYdg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Ou\u00e7a o CD \u201cDecadence and Decay\u201d<\/em><\/strong> <strong><em>via Spotify:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Decadence and Decay\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/5y0jipIofZ3RxXFGcHFGxn?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Assista ao v\u00eddeo clipe de \u201cDivine Fury\u201d<\/em><\/strong> <strong><em>via YouTube:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Silver Talon - Divine Fury (Official Video)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/mBfBEQQcdYc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Cr\u00e9ditos da foto:<\/strong>Peter Beste<\/p>\n\n\n\n<p><strong>Contatos:<\/strong><\/p>\n\n\n\n<p><strong>Site oficial: <\/strong><a href=\"http:\/\/www.silver-talon.com\">www.silver-talon.com<\/a><br><strong>Gravadora: <\/strong><a href=\"http:\/\/www.m-theoryaudio.com\">www.m-theoryaudio.com<\/a><br><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/silvertalonband\">www.facebook.com\/silvertalonband<\/a><br><strong>Bandcamp:\u00a0<\/strong><a href=\"https:\/\/silvertalon.bandcamp.com\">https:\/\/silvertalon.bandcamp.com<\/a><br><strong>Instagram:<\/strong> <a href=\"https:\/\/www.instagram.com\/silvertalon93\/\">https:\/\/www.instagram.com\/silvertalon93<\/a><br><strong>Twitter:<\/strong> <a href=\"https:\/\/twitter.com\/silvertalonband\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/twitter.com\/silvertalonband<\/a><br><strong>YouTube: <\/strong><a href=\"https:\/\/www.youtube.com\/BryceVanHoosen\">https:\/\/www.youtube.com\/BryceVanHoosen<\/a><br><strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor<\/p>\n","protected":false},"author":1,"featured_media":6222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[10,160,162,158,159,25,22],"class_list":["post-6221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-heavy-metal","tag-oregon","tag-portland","tag-power-metal","tag-silver-talon","tag-thrash-metal","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final - Wargods Press<\/title>\n<meta name=\"description\" content=\"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wargods Press - Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final\" \/>\n<meta property=\"og:description\" content=\"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Wargods Press\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T16:41:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T16:41:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Silver-Talon-Press-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Wargods Press - Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final\" \/>\n<meta name=\"twitter:description\" content=\"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Silver-Talon-Press-2025.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final\",\"datePublished\":\"2025-07-18T16:41:10+00:00\",\"dateModified\":\"2025-07-18T16:41:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"heavy metal\",\"Oregon\",\"Portland\",\"Power Metal\",\"Silver Talon\",\"thrash metal\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\",\"name\":\"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final - Wargods Press\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2025-07-18T16:41:10+00:00\",\"dateModified\":\"2025-07-18T16:41:12+00:00\",\"description\":\"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"Wargods Press\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"Wargods Press\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"Wargods Press\"},\"image\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final - Wargods Press","description":"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/","og_locale":"pt_BR","og_type":"article","og_title":"Wargods Press - Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final","og_description":"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).","og_url":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/","og_site_name":"Wargods Press","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2025-07-18T16:41:10+00:00","article_modified_time":"2025-07-18T16:41:12+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Silver-Talon-Press-2025.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_title":"Wargods Press - Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final","twitter_description":"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).","twitter_image":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Silver-Talon-Press-2025.jpg","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/"},"author":{"name":"WarGodsPress","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final","datePublished":"2025-07-18T16:41:10+00:00","dateModified":"2025-07-18T16:41:12+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/"},"wordCount":432,"publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["heavy metal","Oregon","Portland","Power Metal","Silver Talon","thrash metal","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/","url":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/","name":"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final - Wargods Press","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2025-07-18T16:41:10+00:00","dateModified":"2025-07-18T16:41:12+00:00","description":"Os estadunidenses do Silver Talon est\u00e3o a poucos passos de concluir as grava\u00e7\u00f5es de seu novo \u00e1lbum de est\u00fadio, sucessor de \u201cDecadence and Decay\u201d (2021).","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/gravacoes-do-novo-album-do-silver-talon-entram-na-reta-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Grava\u00e7\u00f5es do novo \u00e1lbum do Silver Talon entram na reta final"}]},{"@type":"WebSite","@id":"https:\/\/wargodspress.com.br\/wargods\/#website","url":"https:\/\/wargodspress.com.br\/wargods\/","name":"Wargods Press","description":"Assessoria e Conte\u00fados","publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/wargodspress.com.br\/wargods\/#organization","name":"Wargods Press","url":"https:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"Wargods Press"},"image":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=6221"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6221\/revisions"}],"predecessor-version":[{"id":6223,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6221\/revisions\/6223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/6222"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=6221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=6221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=6221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}