{"id":5030,"date":"2023-09-07T10:42:05","date_gmt":"2023-09-07T13:42:05","guid":{"rendered":"https:\/\/wargodspress.com.br\/wargods\/?p=5030"},"modified":"2023-09-07T10:42:06","modified_gmt":"2023-09-07T13:42:06","slug":"inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/","title":{"rendered":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!"},"content":{"rendered":"\n<p>No dia 29\/09 a banda ga\u00facha <strong>SEGREGATORUM <\/strong>lan\u00e7ar\u00e1 <strong><em>\u201cKirsty\u201d<\/em><\/strong>, o primeiro single de seu novo \u00e1lbum, <strong><em>\u201cPath Worse Than Death\u201d<\/em><\/strong>, acompanhado de um lyric v\u00eddeo produzido por <strong>Maurizio Del Piccolo<\/strong>, que j\u00e1 trabalhou com <strong>Nervosa<\/strong>, <strong>Revolution Saints<\/strong>, <strong>Mr. Big<\/strong>, <strong>Jorn Lande<\/strong> e <strong>Quiet Riot.<\/strong> Com uma bel\u00edssima capa, desenhada pelo artista gr\u00e1fico <strong>Aur\u00e9lio Lara<\/strong>, da <strong>Designlara<\/strong>, e com mixagem assinada pelo renomado produtor <strong>Adair Daufembach<\/strong>, o single traz duas grandes refer\u00eancias em sua tem\u00e1tica: a letra se inspira na cena Death Metal da Fl\u00f3rida entre as d\u00e9cadas de 1980\/1990, cujas letras eram muitas vezes baseadas em filmes de horror, ao mesmo tempo em que tamb\u00e9m homenageia a est\u00e9tica de <strong>Hellraiser<\/strong>, de <strong>Clive Barker. <\/strong>Na m\u00fasica, o narrador parece sentir uma atra\u00e7\u00e3o doentia por atos violentos e sanguin\u00e1rios, descrevendo-os com detalhes perturbadores. O conceito geral da m\u00fasica parece explorar os aspectos mais obscuros e perturbadores da psique humana, bem como a atra\u00e7\u00e3o m\u00f3rbida que alguns indiv\u00edduos podem sentir pela viol\u00eancia e pelo sadismo. \u00c9 uma representa\u00e7\u00e3o art\u00edstica de temas sombrios, t\u00e3o caracter\u00edsticos nos discos de Metal extremo e em filmes de terror e desde o primeiro \u00e1lbum do <strong>SEGREGATORUM <\/strong>uma marca registrada.<\/p>\n\n\n\n<p>A sonoridade do <strong>SEGREGATORUM <\/strong>transcende os limites do convencional, abrangendo uma vasta gama de influ\u00eancias musicais. Ela pode ser apreciada tanto por entusiastas do Death Metal \u00e0 la <strong>Death <\/strong>e <strong>Carcass <\/strong>quanto por aqueles que se deleitam com as nuances complexas e mel\u00f3dicas encontradas em bandas como <strong>Symphony X<\/strong>. O som do grupo \u00e9 verdadeiramente diversificado, refletindo os gostos pessoais e a paleta musical abrangente de seus membros, destacando-se especialmente o vocal vers\u00e1til de <strong>Lucas Lazzarotto<\/strong> e a as linhas de guitarras inspiradas de <strong>Edu Vignatti<\/strong>, encaixando doses intensas de agressividade, peso, melodia e t\u00e9cnica, priorizando bons resultados, independentemente de subg\u00eaneros do Metal.<\/p>\n\n\n\n<p><strong><em>Para fazer o pr\u00e9-save, acesse o link e acompanhe o lan\u00e7amento:<\/em><\/strong><br><a href=\"https:\/\/segregatorum.hearnow.com\/kirsty\">https:\/\/segregatorum.hearnow.com\/kirsty<\/a><\/p>\n\n\n\n<p>A cozinha de <strong><em>\u201cKirsty\u201d<\/em><\/strong> e consequentemente de <strong><em>\u201cPath Worse Than Death\u201d<\/em><\/strong>, traz a participa\u00e7\u00e3o especial do baixista <strong>Alex Carrion<\/strong>, do <strong>Vikram<\/strong>, e do baterista <strong>Thiago Caurio<\/strong>, do <strong>Atomic Elephant<\/strong> e <strong>Keep Them Blind<\/strong>, m\u00fasicos t\u00e9cnicos e gabaritados. A produ\u00e7\u00e3o do \u00e1lbum foi realizada por <strong>Ernani Savaris<\/strong>, do <strong>Soundstorm Studio<\/strong>, localizado na cidade natal do grupo, Bento Gon\u00e7alves. A colabora\u00e7\u00e3o desses m\u00fasicos excepcionais e o envolvimento de <strong>Ernani Savaris<\/strong> garantiram um resultado sonoro de excel\u00eancia para <strong><em>\u201cPath Worse Than Death\u201d<\/em><\/strong>, que ser\u00e1 lan\u00e7ado nos pr\u00f3ximos meses.<\/p>\n\n\n\n<p><strong><em>Ou\u00e7a o single \u201cEmbers Fire\u201d (Paradise Lost cover)<\/em><\/strong><em> <strong>no Spotify:<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Embers Fire (Acoustic) [Cover]\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/1q3erokp8OESpGlMLE29TE?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Ou\u00e7a o single \u201cEmbers Fire\u201d (Paradise Lost cover)<\/em><\/strong><em> <strong>no YouTube:<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Segregatorum - Embers Fire (Paradise Lost Acoustic Cover) (Official)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/OiB4rQy1rKM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Cr\u00e9ditos da foto:<\/strong> Maria Pires<\/p>\n\n\n\n<p><strong>Contatos:<\/strong><\/p>\n\n\n\n<p><strong>Facebook:<\/strong> <a href=\"https:\/\/www.facebook.com\/segregatorummetal\">https:\/\/www.facebook.com\/segregatorummetal<\/a><br><strong>Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/segregatorum\/\">https:\/\/www.instagram.com\/segregatorum<\/a><br><strong>YouTube: <\/strong><a href=\"https:\/\/www.youtube.com\/@segregatorum_Official-Channel\">https:\/\/www.youtube.com\/@segregatorum_Official-Channel<\/a><br><strong>Assessoria de Imprensa:<\/strong> <a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-1024x1024.jpg\" alt=\"\" class=\"wp-image-5031\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-1024x1024.jpg 1024w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-900x900.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-600x600.jpg 600w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-768x768.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single-1536x1536.jpg 1536w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Kirsty-Single.jpg 1760w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>No dia 29\/09 a banda ga\u00facha SEGREGATORUM lan\u00e7ar\u00e1 \u201cKirsty\u201d, o primeiro single de seu novo \u00e1lbum, \u201cPath Worse Than Death\u201d,<\/p>\n","protected":false},"author":1,"featured_media":5032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[204],"class_list":["post-5030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-segregatorum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press<\/title>\n<meta name=\"description\" content=\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press\" \/>\n<meta property=\"og:description\" content=\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\" \/>\n<meta property=\"og:site_name\" content=\"Wargods Press\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T13:42:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T13:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Press-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1970\" \/>\n\t<meta property=\"og:image:height\" content=\"1313\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Press-6.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!\",\"datePublished\":\"2023-09-07T13:42:05+00:00\",\"dateModified\":\"2023-09-07T13:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\"},\"wordCount\":529,\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Segregatorum\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\",\"name\":\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2023-09-07T13:42:05+00:00\",\"dateModified\":\"2023-09-07T13:42:06+00:00\",\"description\":\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"Wargods Press\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"Wargods Press\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"Wargods Press\"},\"image\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press","description":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/","og_locale":"pt_BR","og_type":"article","og_title":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press","og_description":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!","og_url":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/","og_site_name":"Wargods Press","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2023-09-07T13:42:05+00:00","article_modified_time":"2023-09-07T13:42:06+00:00","og_image":[{"width":1970,"height":1313,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Press-6.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_image":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2023\/09\/Segregatorum-Press-6.jpg","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/"},"author":{"name":"WarGodsPress","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!","datePublished":"2023-09-07T13:42:05+00:00","dateModified":"2023-09-07T13:42:06+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/"},"wordCount":529,"publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Segregatorum"],"articleSection":["News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/","url":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/","name":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save! - Wargods Press","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2023-09-07T13:42:05+00:00","dateModified":"2023-09-07T13:42:06+00:00","description":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/inspirado-no-death-metal-da-florida-e-na-estetica-de-hellraiser-single-kirsty-sera-lancado-no-final-do-mes-confira-capa-e-pre-save\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Inspirado no Death Metal da Fl\u00f3rida e na est\u00e9tica de Hellraiser, single \u201cKirsty\u201d ser\u00e1 lan\u00e7ado no final do m\u00eas; confira capa e pr\u00e9-save!"}]},{"@type":"WebSite","@id":"https:\/\/wargodspress.com.br\/wargods\/#website","url":"https:\/\/wargodspress.com.br\/wargods\/","name":"Wargods Press","description":"Assessoria e Conte\u00fados","publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/wargodspress.com.br\/wargods\/#organization","name":"Wargods Press","url":"https:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"Wargods Press"},"image":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/5030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=5030"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/5030\/revisions"}],"predecessor-version":[{"id":5033,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/5030\/revisions\/5033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/5032"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=5030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=5030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=5030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}