{"id":3071,"date":"2021-07-06T18:51:19","date_gmt":"2021-07-06T21:51:19","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=3071"},"modified":"2021-07-06T18:51:19","modified_gmt":"2021-07-06T21:51:19","slug":"overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/","title":{"rendered":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-3072\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio-900x576.jpg\" alt=\"\" width=\"900\" height=\"576\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio-900x576.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio-768x491.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Lan\u00e7ado em maio de 2019, o debut autointitulado da banda <strong>OVERDOSE NUCLEAR <\/strong>agora ganha um mini-document\u00e1rio de suas grava\u00e7\u00f5es, realizadas em 2018 no est\u00fadio <strong>Family Mob<\/strong>, em S\u00e3o Paulo. O t\u00edtulo do DOC, <strong><em>\u201cDos Urros ao Mangue\u201d<\/em><\/strong>, evoca tamb\u00e9m os prim\u00f3rdios da banda, fazendo refer\u00eancia \u00e0 demo <strong>\u201c<em>Os Urros que v\u00eam da rua!\u201d<\/em><\/strong><em>, <\/em>de 2015. Desde ent\u00e3o o grupo trilhou um caminho pr\u00f3prio, incluindo influ\u00eancias diversas \u00e0 sua sonoridade, indo do Heavy Metal cl\u00e1ssico ao Thrash Metal com muita personalidade, expondo todas as mazelas da sociedade atrav\u00e9s de m\u00fasicas cantadas em nossa l\u00edngua natal. Como grupo faz quest\u00e3o de frisar, <em>\u201co litoral norte de S\u00e3o Paulo n\u00e3o \u00e9 feito somente de sol, belas praias, mata atl\u00e2ntica nativa e gente andando seminua, mas tamb\u00e9m feito de muita chuva, lugares esquecidos por Deus, mis\u00e9ria, juventude sem esperan\u00e7a, corrup\u00e7\u00e3o e abandono da popula\u00e7\u00e3o pelos governantes\u201d. <\/em><\/p>\n<p><strong><em>Assista ao DOC \u201cDos Urros ao Mangue\u201d:<br \/>\n<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/y-NmRq5vUGk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen title=\"Mini Document\u00e1rio - Dos Urros ao Mangue\"><\/iframe><\/p>\n<p>Vindos de Ubatuba, <strong>Samuel Marques<\/strong> (bateria), <strong>Gustavo Albado <\/strong>(baixo), <strong>Marcus Goulart<\/strong> (guitarra) e <strong>Julio Candinho<\/strong> (vocal) ao mesmo tempo que relembram as grava\u00e7\u00f5es do debut, j\u00e1 trabalham em seu sucessor, com lan\u00e7amento previsto para 2022, quando a banda completar\u00e1 10 anos de estrada. E as mesmas palavras ditas acima sobre toda a desesperan\u00e7a ser\u00e3o retratadas neste novo \u00e1lbum, como conta o vocalista <strong>Julio Candinho<\/strong>: <em>\u201cAcho que toda banda de Metal que se preze e que tenha como foco falar sobre os problemas sociais sempre ter\u00e1 assunto. Com a pandemia vimos o pior do ser humano, seja na pr\u00f3pria sociedade quanto na pol\u00edtica. As mesmas palavras que usamos para divulgar o debut podemos usar agora: N\u00e3o vemos mais o futuro como algo a ser sonhado, sim algo que para ser temido, um futuro claustrof\u00f3bico como se estiv\u00e9ssemos presos nas teias da destrui\u00e7\u00e3o\u201d.<\/em><\/p>\n<p><strong><em>Assista ao v\u00eddeo clipe de \u201cKriatura\u201d:<br \/>\n<\/em><\/strong><a href=\"https:\/\/www.youtube.com\/watch?v=YlDI0PClVkc\">https:\/\/www.youtube.com\/watch?v=YlDI0PClVkc<\/a><\/p>\n<p><strong><em>Ou\u00e7a \u201cOverdose Nuclear\u201d no Spotify:<\/em><\/strong><\/p>\n<p><iframe style=\"border-radius: 12px\" width=\"100%\" height=\"380\" title=\"Spotify Embed: Overdose Nuclear\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/1vxMOvyZ5sGC891b9yzsID?si=&#038;utm_source=oembed\"><\/iframe><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Site oficial: <\/strong><a href=\"http:\/\/www.overdosenuclear.com.br\">www.overdosenuclear.com.br<\/a><br \/>\n<strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/OverdoseNuclear\">www.facebook.com\/OverdoseNuclear<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/overdosenuclear\">www.instagram.com\/overdosenuclear<\/a><br \/>\n<strong>E-mail: <\/strong><a href=\"mailto:contato@overdosenuclear.com\">contato@overdosenuclear.com<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-194\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/01\/Overdose-Nuclear-Capa.jpg\" alt=\"\" width=\"768\" height=\"768\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/01\/Overdose-Nuclear-Capa.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/01\/Overdose-Nuclear-Capa-600x600.jpg 600w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lan\u00e7ado em maio de 2019, o debut autointitulado da banda OVERDOSE NUCLEAR agora ganha um mini-document\u00e1rio de suas grava\u00e7\u00f5es, realizadas<\/p>\n","protected":false},"author":1,"featured_media":3072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[431,3,367],"tags":[432,131,31,25,119,22],"class_list":["post-3071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentarios","category-news","category-videos","tag-documentario","tag-metal-do-mangue","tag-overdose-nuclear","tag-thrash-metal","tag-ubatuba","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press\" \/>\n<meta property=\"og:description\" content=\"Lan\u00e7ado em maio de 2019, o debut autointitulado da banda OVERDOSE NUCLEAR agora ganha um mini-document\u00e1rio de suas grava\u00e7\u00f5es, realizadas\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\" \/>\n<meta property=\"og:site_name\" content=\"Wargods Press\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-06T21:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista!\",\"datePublished\":\"2021-07-06T21:51:19+00:00\",\"dateModified\":\"2021-07-06T21:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\"},\"wordCount\":400,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Document\u00e1rio\",\"Metal do Mangue\",\"Overdose Nuclear\",\"thrash metal\",\"Ubatuba\",\"Wargods Press\"],\"articleSection\":[\"Document\u00e1rios\",\"News\",\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\",\"name\":\"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2021-07-06T21:51:19+00:00\",\"dateModified\":\"2021-07-06T21:51:19+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"Wargods Press\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"Wargods Press\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"Wargods Press\"},\"image\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/","og_locale":"pt_BR","og_type":"article","og_title":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press","og_description":"Lan\u00e7ado em maio de 2019, o debut autointitulado da banda OVERDOSE NUCLEAR agora ganha um mini-document\u00e1rio de suas grava\u00e7\u00f5es, realizadas","og_url":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/","og_site_name":"Wargods Press","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2021-07-06T21:51:19+00:00","og_image":[{"width":1024,"height":655,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/07\/Overdose-Nuclear-Document\u00e1rio.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/"},"author":{"name":"WarGodsPress","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista!","datePublished":"2021-07-06T21:51:19+00:00","dateModified":"2021-07-06T21:51:19+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/"},"wordCount":400,"commentCount":0,"publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Document\u00e1rio","Metal do Mangue","Overdose Nuclear","thrash metal","Ubatuba","Wargods Press"],"articleSection":["Document\u00e1rios","News","V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/","url":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/","name":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista! - Wargods Press","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2021-07-06T21:51:19+00:00","dateModified":"2021-07-06T21:51:19+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/overdose-nuclear-mini-documentario-dos-urros-ao-mangue-e-lancado-assista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Overdose Nuclear: Mini-document\u00e1rio \u201cDos Urros ao Mangue\u201d \u00e9 lan\u00e7ado; assista!"}]},{"@type":"WebSite","@id":"https:\/\/wargodspress.com.br\/wargods\/#website","url":"https:\/\/wargodspress.com.br\/wargods\/","name":"Wargods Press","description":"Assessoria e Conte\u00fados","publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/wargodspress.com.br\/wargods\/#organization","name":"Wargods Press","url":"https:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"Wargods Press"},"image":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/3071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=3071"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/3071\/revisions"}],"predecessor-version":[{"id":3073,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/3071\/revisions\/3073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/3072"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=3071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=3071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=3071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}