{"id":2958,"date":"2021-05-27T10:54:28","date_gmt":"2021-05-27T13:54:28","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=2958"},"modified":"2021-05-27T10:55:41","modified_gmt":"2021-05-27T13:55:41","slug":"fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/","title":{"rendered":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2730 aligncenter\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021-900x614.jpg\" alt=\"Fighter: Participa\u00e7\u00e3o confirmada no festival da Roadie Crew nesta sexta\" width=\"784\" height=\"535\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021-900x614.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021-768x524.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021.jpg 1024w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/p>\n<p>A banda ga\u00facha <strong>FIGHTER <\/strong>acaba de lan\u00e7ar um v\u00eddeo da faixa <strong><em>\u201cLiberdade\u201d<\/em><\/strong>, tamb\u00e9m disponibilizada em todas as plataformas digitais. A m\u00fasica \u00e9 uma vers\u00e3o &#8220;2.0&#8221; da vers\u00e3o original, gravada no EP <strong><em>&#8220;Feeling&#8221;<\/em><\/strong> (2019). Nessa releitura, ao inv\u00e9s de ac\u00fastica, a banda pesou o arranjo dando uma vibe &#8220;arena&#8221; a l\u00e1 grandes cl\u00e1ssicos\/baladas dos anos 80. A vers\u00e3o vem no embalo de <strong><em>&#8220;Cora\u00e7\u00e3o Alado&#8221;<\/em><\/strong> (ao vivo) gravada para o festival da <strong>Roadie Crew<\/strong>, servindo de aquecimento para o primeiro lan\u00e7amento in\u00e9dito do EP, <strong><em>&#8220;A For\u00e7a&#8221;<\/em><\/strong>, que chega no final de junho. Tanto esta nova leitura de <strong><em>&#8220;Liberdade&#8221;<\/em><\/strong> quanto <strong><em>&#8220;Cora\u00e7\u00e3o Alado&#8221;<\/em><\/strong> (ao vivo) ser\u00e3o consideradas b\u00f4nus do vindouro EP <strong><em>&#8220;A For\u00e7a&#8221;<\/em><\/strong>.<\/p>\n<p>Trabalhando sem cessar, o grupo formado por <strong>Cesar Branco\u00a0<\/strong>(vocal),\u00a0<strong>Alexsandro Gabrielli <\/strong>(guitarra e backing vocal),\u00a0<strong>Gustavo Refosco <\/strong>(baixo) e\u00a0<strong>Guilherme Adamatti\u00a0<\/strong>(bateria) promete novidades em rela\u00e7\u00e3o ao EP, inclusive com uma participa\u00e7\u00e3o especial de peso, que ser\u00e1 revelada em breve. A quest\u00e3o \u00e9: a <strong>FIGHTER<\/strong> tem se dedicado ao m\u00e1ximo, como conta <strong>Cesar Branco<\/strong>: <em>\u201cNestes cerca de 13 anos de estrada nunca paramos e estamos mais ativos do que nunca. Do in\u00edcio de 2020 para c\u00e1 lan\u00e7amos o ao vivo <\/em><em>\u201cVII\u201d nas plataformas digitais, acompanhado de um v\u00eddeo exclusivo do \u00e1lbum por m\u00eas, al\u00e9m de diversos singles e v\u00eddeos, isso sem contar as lives e participa\u00e7\u00f5es em festivais online. O que mais queremos agora \u00e9 voltar aos palcos e mostrar todo esse material ao vivo! Continuem acompanhando a banda que vem muita novidade por a\u00ed!\u201d.<\/em><\/p>\n<p><strong><em>Assista ao v\u00eddeo de \u201cLiberdade\u201d:<br \/>\n<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/mrIWfWYmzV8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen title=\"FIGHTER - Liberdade\"><\/iframe><\/p>\n<p><strong><em>Ou\u00e7a \u201cLiberdade\u201d no Spotify:<br \/>\n<\/em><\/strong><\/p>\n<p><iframe style=\"border-radius: 12px\" width=\"100%\" height=\"152\" title=\"Spotify Embed: Liberdade\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/track\/1fuRiQ5YOI2Opy6shzftCr?utm_source=oembed\"><\/iframe><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Telegram: <\/strong><a href=\"https:\/\/t.me\/fighter_banda\">https:\/\/t.me\/fighter_banda<\/a><br \/>\n<strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/bandafighter\">www.facebook.com\/bandafighter<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/fighter_banda\">www.instagram.com\/fighter_banda<\/a><br \/>\n<strong>Youtube:<\/strong> <a href=\"http:\/\/www.youtube.com\/fighterhardrock\">www.youtube.com\/fighterhardrock<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A banda ga\u00facha FIGHTER acaba de lan\u00e7ar um v\u00eddeo da faixa \u201cLiberdade\u201d, tamb\u00e9m disponibilizada em todas as plataformas digitais. A<\/p>\n","protected":false},"author":1,"featured_media":2730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,168,367],"tags":[220,22],"class_list":["post-2958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-plataformas-digitais","category-videos","tag-fighter","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"A banda ga\u00facha FIGHTER acaba de lan\u00e7ar um v\u00eddeo da faixa \u201cLiberdade\u201d, tamb\u00e9m disponibilizada em todas as plataformas digitais. A\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T13:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-27T13:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d\",\"datePublished\":\"2021-05-27T13:54:28+00:00\",\"dateModified\":\"2021-05-27T13:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"fighter\",\"Wargods Press\"],\"articleSection\":[\"News\",\"Plataformas Digitais\",\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\",\"name\":\"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2021-05-27T13:54:28+00:00\",\"dateModified\":\"2021-05-27T13:55:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/","og_locale":"pt_BR","og_type":"article","og_title":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026","og_description":"A banda ga\u00facha FIGHTER acaba de lan\u00e7ar um v\u00eddeo da faixa \u201cLiberdade\u201d, tamb\u00e9m disponibilizada em todas as plataformas digitais. A","og_url":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2021-05-27T13:54:28+00:00","article_modified_time":"2021-05-27T13:55:41+00:00","og_image":[{"width":1024,"height":699,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/02\/Fighter-Promo-2021.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d","datePublished":"2021-05-27T13:54:28+00:00","dateModified":"2021-05-27T13:55:41+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["fighter","Wargods Press"],"articleSection":["News","Plataformas Digitais","V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/","url":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/","name":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2021-05-27T13:54:28+00:00","dateModified":"2021-05-27T13:55:41+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/fighter-banda-gaucha-lanca-video-com-nova-versao-de-liberdade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Fighter: Banda ga\u00facha lan\u00e7a v\u00eddeo com nova vers\u00e3o de \u201cLiberdade\u201d"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=2958"}],"version-history":[{"count":2,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2958\/revisions"}],"predecessor-version":[{"id":2960,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2958\/revisions\/2960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/2730"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=2958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=2958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=2958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}