{"id":2635,"date":"2021-01-14T13:47:50","date_gmt":"2021-01-14T15:47:50","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=2635"},"modified":"2021-01-14T13:48:22","modified_gmt":"2021-01-14T15:48:22","slug":"the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/","title":{"rendered":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2129\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020-900x600.jpg\" alt=\"\" width=\"813\" height=\"542\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020-900x600.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020-768x512.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" \/><\/p>\n<p>O <strong>THE ANGER<\/strong> est\u00e1 de volta para divulgar mais um single de seu pr\u00f3ximo disco, <strong><em>&#8220;Tales from the City&#8221;<\/em><\/strong>. Ap\u00f3s <strong><em>&#8220;I Walk Alone&#8221;<\/em><\/strong> e <strong><em>&#8220;Vote for Me&#8221;<\/em><\/strong>, \u00e9 a vez de <strong><em>&#8220;Ghosts&#8221; <\/em><\/strong>chegar nas plataformas digitais. A m\u00fasica traz uma letra inspirada em moradores de rua, sob uma perspectiva musical que ironiza a situa\u00e7\u00e3o.<em> &#8220;As pessoas n\u00e3o se importam com moradores de rua at\u00e9 que eles se mostrem pessoas reais, com talentos e aspira\u00e7\u00f5es. \u00c0s vezes, nem assim. Mas meu intuito \u00e9 chamar a aten\u00e7\u00e3o juntando a letra triste com uma m\u00fasica animada&#8221;<\/em> explica <strong>Rafael Orsi<\/strong>, compositor (guitarra, baixo e backing vocal). Al\u00e9m de Rafael, essa m\u00fasica conta com <strong>F\u00e1bio Moyses<\/strong> na bateria e <strong>Aivan Moura<\/strong> na voz principal.<\/p>\n<p><strong><em>Fa\u00e7a o pre-save no Spotify<\/em><\/strong><em>:<br \/>\n<\/em><a href=\"https:\/\/distrokid.com\/hyperfollow\/theanger\/ghosts\"><em>https:\/\/distrokid.com\/hyperfollow\/theanger\/ghosts<\/em><\/a><em><br \/>\n<\/em><br \/>\nA m\u00fasica receber\u00e1 um lyric v\u00eddeo a ser lan\u00e7ado no mesmo dia no YouTube e no Facebook e foi criado pelo pr\u00f3prio guitarrista, que tamb\u00e9m foi o respons\u00e1vel pela arte da capa.<\/p>\n<p><strong><em>Ative o lembrete para o lan\u00e7amento do lyric video.<br \/>\n<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/1RAnyVDnbvs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen title=\"The Anger - Ghosts (Official Lyric Video)\"><\/iframe><\/p>\n<p><strong><em>Ou\u00e7a \u201cVote For Me\u201d no Spotify:<br \/>\n<\/em><\/strong><\/p>\n<p><iframe style=\"border-radius: 12px\" width=\"100%\" height=\"380\" title=\"Spotify Embed: Vote for Me\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/5B1YDtMNWV95upizPFNJVy?utm_source=oembed\"><\/iframe><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Ou\u00e7a: <\/strong><a href=\"https:\/\/linktr.ee\/theanger\">https:\/\/linktr.ee\/theanger<\/a><br \/>\n<strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/theangerband\">www.facebook.com\/theangerband<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/theangerband\">www.instagram.com\/theangerband<\/a><br \/>\n<strong>Youtube:<\/strong> <a href=\"http:\/\/www.youtube.com\/rafaelorsi\">www.youtube.com\/rafaelorsi<\/a><br \/>\n<strong>Assessoria de Imprensa:<\/strong> <a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2636\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/01\/The-Anger-Ghosts.jpg\" alt=\"\" width=\"666\" height=\"666\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/01\/The-Anger-Ghosts.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2021\/01\/The-Anger-Ghosts-600x600.jpg 600w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O THE ANGER est\u00e1 de volta para divulgar mais um single de seu pr\u00f3ximo disco, &#8220;Tales from the City&#8221;. Ap\u00f3s<\/p>\n","protected":false},"author":1,"featured_media":2129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[217,22],"class_list":["post-2635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-the-anger","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press\" \/>\n<meta property=\"og:description\" content=\"O THE ANGER est\u00e1 de volta para divulgar mais um single de seu pr\u00f3ximo disco, &#8220;Tales from the City&#8221;. Ap\u00f3s\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\" \/>\n<meta property=\"og:site_name\" content=\"Wargods Press\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-14T15:47:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-14T15:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4000\" \/>\n\t<meta property=\"og:image:height\" content=\"2667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save\",\"datePublished\":\"2021-01-14T15:47:50+00:00\",\"dateModified\":\"2021-01-14T15:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"The Anger\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\",\"name\":\"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2021-01-14T15:47:50+00:00\",\"dateModified\":\"2021-01-14T15:48:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"Wargods Press\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"Wargods Press\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"Wargods Press\"},\"image\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/","og_locale":"pt_BR","og_type":"article","og_title":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press","og_description":"O THE ANGER est\u00e1 de volta para divulgar mais um single de seu pr\u00f3ximo disco, &#8220;Tales from the City&#8221;. Ap\u00f3s","og_url":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/","og_site_name":"Wargods Press","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2021-01-14T15:47:50+00:00","article_modified_time":"2021-01-14T15:48:22+00:00","og_image":[{"width":4000,"height":2667,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/09\/The-Anger-Press-2020.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/"},"author":{"name":"WarGodsPress","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save","datePublished":"2021-01-14T15:47:50+00:00","dateModified":"2021-01-14T15:48:22+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["The Anger","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/","url":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/","name":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save - Wargods Press","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2021-01-14T15:47:50+00:00","dateModified":"2021-01-14T15:48:22+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/the-anger-novo-single-sera-lancado-no-final-de-janeiro-faca-o-pre-save\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"The Anger: Novo single ser\u00e1 lan\u00e7ado no final de janeiro; fa\u00e7a o pre-save"}]},{"@type":"WebSite","@id":"https:\/\/wargodspress.com.br\/wargods\/#website","url":"https:\/\/wargodspress.com.br\/wargods\/","name":"Wargods Press","description":"Assessoria e Conte\u00fados","publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/wargodspress.com.br\/wargods\/#organization","name":"Wargods Press","url":"https:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"Wargods Press"},"image":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=2635"}],"version-history":[{"count":2,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2635\/revisions"}],"predecessor-version":[{"id":2638,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2635\/revisions\/2638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/2129"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=2635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=2635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=2635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}