{"id":1821,"date":"2020-06-04T14:51:59","date_gmt":"2020-06-04T17:51:59","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1821"},"modified":"2020-06-04T14:51:59","modified_gmt":"2020-06-04T17:51:59","slug":"solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/","title":{"rendered":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais"},"content":{"rendered":"<figure id=\"attachment_1252\" aria-describedby=\"caption-attachment-1252\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1252\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press-900x679.jpg\" alt=\"\" width=\"900\" height=\"679\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press-900x679.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press-768x579.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press-1024x772.jpg 1024w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press.jpg 1440w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-1252\" class=\"wp-caption-text\">Solarisphere<\/figcaption><\/figure>\n<p>A banda <strong>SOLARISPHERE, <\/strong>de Rondon\u00f3polis\/MT, acaba de lan\u00e7ar seu primeiro EP, auto intitulado, em todas as plataformas digitais. Disponibilizado atrav\u00e9s da Wargods Press, o EP apresenta quatro faixas, que traduzem de forma singular influ\u00eancias baseadas no Stoner Rock\/Heavy Metal, com Caio C\u00e9sar (baixo\/vocal), Lucas Codorniz e Rafael Mafra (guitarras) e Nelson J\u00fanior (bateria) adicionando suas pr\u00f3prias caracter\u00edsticas \u00e0s m\u00fasicas, conduzindo os ouvintes para uma viagem sonora aut\u00eantica e empolgante. \u201c<em>Fade\u201d, \u201cMy Mind\u201d, \u201cSlime\u201d<\/em> e <em>\u201cLost Thoughts\u201d <\/em>foram trabalhadas nos m\u00ednimos detalhes, como conta o baixista e vocalista Caio C\u00e9sar: <em>\u201cPassamos os \u00faltimos meses praticamente em est\u00fadio, moldando cada m\u00fasica at\u00e9 chegarmos ao ponto certo. Contamos com a grande parceria do produtor Nelson Martins e acreditamos que o resultado final tenha ficado excelente! O lan\u00e7amento do EP \u00e9 uma vit\u00f3ria, afinal, estamos no meio de uma pandemia e de agora em diante as coisas ser\u00e3o bem diferentes, mas esperamos que nossas m\u00fasicas ajudem os f\u00e3s de som pesado a encarar tudo de uma forma diferente\u201d.\u00a0<\/em><em>\u00a0<\/em><\/p>\n<p><strong><em>Ou\u00e7a o EP no Spotify:<br \/>\n<\/em><\/strong><a href=\"https:\/\/open.spotify.com\/album\/5REbwlqX2uFIrk7BQowuzn\"><em>https:\/\/open.spotify.com\/album\/5REbwlqX2uFIrk7BQowuzn<\/em><\/a><\/p>\n<p>Em rela\u00e7\u00e3o a tem\u00e1tica abordada nas letras, o baixista e vocalista Caio C\u00e9sar explica que as m\u00fasicas falam basicamente de assuntos retratam situa\u00e7\u00f5es pessoais de supera\u00e7\u00e3o, como <em>\u201cMy Mind\u201d<\/em>: <em>\u201cA m\u00fasica fala de f<\/em><em>ormas de superar algo que ficou no passado e maneiras utilizadas para lidar com o mesmo. Eu compus essa letra baseado em um t\u00e9rmino de relacionamento e na forma de super\u00e1-lo\u201d.<\/em> A letra de <em>\u201cFade\u201d<\/em> trabalha sobre a desilus\u00e3o da vida, e segundo o m\u00fasico, <em>\u201cde como a rotina se torna c\u00f4moda e, de certa forma, acabamos no tornando prisioneiros dela. Procuro transmitir um alerta sobre como vivemos uma mentira e a necessidade de acordarmos\u201d.<\/em> <em>\u201cLost Thoughts\u201d<\/em>, entretanto, trabalha a ideia de uma pessoa que supostamente possui o controle, apenas para perceber que, no final das contas, ela era apenas mais uma pe\u00e7a da roda da vida. Segundo Caio, <em>\u201ceu meio que fiz a letra seguindo o imagin\u00e1rio de um executor que, em determinado momento chave, percebe que quem \u00e9 o pr\u00f3ximo a ser executado \u00e9 ele mesmo\u201d.\u00a0 <\/em>Por fim, <em>\u201cThe Slime\u201d<\/em> retrata a hist\u00f3ria de um assassino: <em>\u201cUma v\u00edtima que, ao ser criada na fossa e de maneiras impr\u00f3prias, se tornou um ser que procura atrair suas v\u00edtimas a seu habitat para dissolver as mesmas. Em resumo, a letra retrata a forma como ele atrai uma mo\u00e7a at\u00e9 a mesma, a executa e, no fim, se sente sozinho por novamente estar em suas trevas\u201d.<\/em><\/p>\n<p>A bel\u00edssima capa do EP foi criada pelo artista gr\u00e1fico Rafael Panegalli, com ideias sugeridas pela banda, como explicou Nelson J\u00fanior: <em>\u201cQuando o Rafael nos entregou a arte pronta ficamos malucos! A primeira coisa que pensamos foi: imagina um bolach\u00e3o de vinil com essa capa? Pode ser um plano meio louco, mas gostar\u00edamos que rolasse. Para compor a arte, passamos algumas ideias para ele e o resultado ficou lindo, casando perfeitamente com nosso conceito\u201d. <\/em>Segundo a banda, h\u00e1 a inten\u00e7\u00e3o de lan\u00e7ar a vers\u00e3o f\u00edsica do EP, mas com a pandemia os planos ser\u00e3o adiados para quando houver um cen\u00e1rio de normaliza\u00e7\u00e3o. Para breve o <strong>SOLARISPHERE <\/strong>planeja a\u00e7\u00f5es virtuais para a promo\u00e7\u00e3o do material e mais novidades ser\u00e3o divulgadas em breve.<em>\u00a0<\/em><\/p>\n<p><strong><em>Ou\u00e7a o EP no Deezer:<br \/>\n<\/em><\/strong><a href=\"https:\/\/www.deezer.com\/br\/album\/151976052\"><em>https:\/\/www.deezer.com\/br\/album\/151976052<\/em><\/a><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/solarisphere\">www.facebook.com\/solarisphere<\/a><br \/>\n<strong>Soundcloud:<\/strong> <a href=\"http:\/\/www.soundcloud.com\/solarisphererock\">www.soundcloud.com\/solarisphererock<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/solarisphereroo\">www.instagram.com\/solarisphereroo<\/a><br \/>\n<strong>Assessoria de Imprensa:\u00a0 <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1789\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa-900x900.jpg\" alt=\"\" width=\"900\" height=\"900\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa-900x900.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa-600x600.jpg 600w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa-768x768.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa-1024x1024.jpg 1024w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/05\/Solarisphere-Capa.jpg 1697w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A banda SOLARISPHERE, de Rondon\u00f3polis\/MT, acaba de lan\u00e7ar seu primeiro EP, auto intitulado, em todas as plataformas digitais. Disponibilizado atrav\u00e9s<\/p>\n","protected":false},"author":1,"featured_media":1252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,168],"tags":[198,22],"class_list":["post-1821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-plataformas-digitais","tag-solarisphere","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"A banda SOLARISPHERE, de Rondon\u00f3polis\/MT, acaba de lan\u00e7ar seu primeiro EP, auto intitulado, em todas as plataformas digitais. Disponibilizado atrav\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T17:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1086\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais\",\"datePublished\":\"2020-06-04T17:51:59+00:00\",\"dateModified\":\"2020-06-04T17:51:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Solarisphere\",\"Wargods Press\"],\"articleSection\":[\"News\",\"Plataformas Digitais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\",\"name\":\"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2020-06-04T17:51:59+00:00\",\"dateModified\":\"2020-06-04T17:51:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/","og_locale":"pt_BR","og_type":"article","og_title":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026","og_description":"A banda SOLARISPHERE, de Rondon\u00f3polis\/MT, acaba de lan\u00e7ar seu primeiro EP, auto intitulado, em todas as plataformas digitais. Disponibilizado atrav\u00e9s","og_url":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2020-06-04T17:51:59+00:00","og_image":[{"width":1440,"height":1086,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/10\/Solisphere-Press.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais","datePublished":"2020-06-04T17:51:59+00:00","dateModified":"2020-06-04T17:51:59+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Solarisphere","Wargods Press"],"articleSection":["News","Plataformas Digitais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/","url":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/","name":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2020-06-04T17:51:59+00:00","dateModified":"2020-06-04T17:51:59+00:00","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/solarisphere-primeiro-ep-e-liberado-em-todas-as-plataformas-digitais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Solarisphere: Primeiro EP \u00e9 liberado em todas as plataformas digitais"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1821"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1821\/revisions"}],"predecessor-version":[{"id":1822,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1821\/revisions\/1822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/1252"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}