{"id":1681,"date":"2020-04-17T11:21:44","date_gmt":"2020-04-17T14:21:44","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1681"},"modified":"2020-04-17T11:21:44","modified_gmt":"2020-04-17T14:21:44","slug":"hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/","title":{"rendered":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa"},"content":{"rendered":"<figure id=\"attachment_1470\" aria-describedby=\"caption-attachment-1470\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1470\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2-900x601.jpg\" alt=\"\" width=\"900\" height=\"601\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2-900x601.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2-768x513.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-1470\" class=\"wp-caption-text\">Hell Gun<\/figcaption><\/figure>\n<p>Cercados de expectativas, o <strong>Hell Gun<\/strong>, do Paran\u00e1, est\u00e1 divulgando mais informa\u00e7\u00f5es sobre seu primeiro \u00e1lbum, <em>\u201cKings of Beyond\u201d<\/em>, que ser\u00e1 lan\u00e7ado no segundo semestre atrav\u00e9s da Classic Metal Records, selo especializado em Heavy Metal tradicional e vertentes mais cl\u00e1ssicas do som pesado. Matheus Luciano (vocal),\u00a0 Lucas Licheski e Jean Fallas\u00a0 (guitarras), Marllon Woicizack (baixo) e Sidnei Dubiella (bateria) mostram-se confiantes com a parceria: <em>\u201cA Classic Metal, \u00e9, antes de tudo, um verdadeiro santu\u00e1rio para quem curte Heavy tradicional, NWOTHM, NWOBHM, Speed Metal e todas aquelas bandas que amamos tanto. Seja relan\u00e7ando material cl\u00e1ssico ou apostando em bandas novas, o trabalho deles \u00e9 refer\u00eancia, e n\u00e3o poder\u00edamos ficar mais satisfeitos em fechar essa parceria com o D\u00eanis e com a Patr\u00edcia. Eles realmente amam o que fazem e \u00e9 isso o que os torna um diferencial\u201d. <\/em><\/p>\n<p>A Classic Metal Records \u00e9 especializada na venda de CDs, DVDs, LPs e artigos de Rock and Roll e Heavy Metal desde seu in\u00edcio, em 2006. Dez anos depois a loja ampliou seus trabalhos para se tornar um selo, realizando lan\u00e7amentos de \u00e1lbuns de Rock e Metal, mas com foco no Heavy Metal dos anos 80. Denis Pedro Zuliano e Patricia Vera tem apostado n\u00e3o somente em material internacional, mas tamb\u00e9m em bandas brasileiras, como \u00e9 o caso da\u00a0 <strong>Hell Gun<\/strong>, que ter\u00e1 seu CD debut lan\u00e7ado pelo selo. Nas palavras de Denis e Patricia, a o grupo paranaense \u00e9 o retrato fiel do Heavy Metal cl\u00e1ssico oitentista: <em>\u201cA sonoridade da banda nos remete imediatamente \u00e0 fase \u00e1urea do Metal, e a pr\u00f3pria atitude da banda faz jus a esta caracter\u00edstica, tornando \u201c<\/em><em>Kings of Beyond\u201d um material empolgante do inicio ao fim. Ficamos muito felizes com essa parceria e daqui pra frente teremos muito prazer em levar o nome da banda o mais longe poss\u00edvel!\u201d.<\/em><\/p>\n<p><strong><em>Confira um teaser do \u00e1lbum pela Classic Metal Records:<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wH9hWDeXWBk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/em><\/strong><\/p>\n<p><em>\u00a0<\/em><em>\u201cKings of Beyond\u201d <\/em>est\u00e1 sendo finalizado pelo produtor Arthur Migotto, do Heavytron Sound Studio, est\u00fadio especializado em Rock e Heavy old school, que j\u00e1 trabalhou com as bandas Nosferatu (mix), Grey Wolf (mix) e Witchtrap (remaster). Arthur, que j\u00e1\u00a0 foi vocalista de outro grande nome do Metal paranaense, o Hazy Hamlet, e atualmente est\u00e1 a frente do Coltan Skull, d\u00e1 sua opini\u00e3o sobre o trabalho desenvolvido com a banda: <em>\u201cAo longo dos \u00faltimos meses trabalhamos coma afinco nas grava\u00e7\u00f5es e produ\u00e7\u00e3o do \u00e1lbum, e o que pude ver at\u00e9 agora foi uma banda talentosa e cheia de feeling, o que far\u00e1 de \u201cKings of Beyond\u201d um verdadeiro sucesso entre os apreciadores de uma sonoridade voltada ao Heavy\/Speed Metal\u201d.<\/em><\/p>\n<p>Para aquecer o p\u00fablico, a banda lan\u00e7ou o single <em>\u201cRevolution Blade\u201d<\/em> acompanhado de um v\u00eddeo clipe, que ao vivo j\u00e1 teve aprova\u00e7\u00e3o total. Para o vocalista Matheus Luciano, a expectativa \u00e9 alta: <em>\u201cA forte parceria com Arthur Migotto e Classic Metal Records tem dado a banda muita energia, fundamental neste momento. N\u00e3o cont\u00e1vamos com uma pandemia mundial em nossos planos, mas a banda segue trabalhando e o resultado final ser\u00e1 o \u201cKings of Beyond\u201d, um \u00e1lbum que reunir\u00e1 doses maci\u00e7as de paix\u00e3o e feeling!\u201d. <\/em>Com a capa desenhada por Giovanne Bernardino, o <strong>Hell Gun <\/strong>segue abrindo espa\u00e7o para <em>\u201cKings of Beyond\u201d, <\/em>que dever\u00e1\u00a0 ganhar mais um single no pr\u00f3ximo m\u00eas.<\/p>\n<p><strong><em>Assista ao v\u00eddeo clipe de \u201cRevolution Blade\u201d:<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/QiiHA9WDwFI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/em><\/strong><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook:<\/strong> <a href=\"http:\/\/www.facebook.com\/bandaHellGun\">www.facebook.com\/bandaHellGun<\/a><br \/>\n<strong>Instagram:<\/strong> <a href=\"http:\/\/www.instagram.com\/hellgun_official\">www.instagram.com\/hellgun_official<\/a><br \/>\n<strong>Gravadora:<\/strong> <a href=\"http:\/\/www.classicmetal.com.br\">www.classicmetal.com.br<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1682\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Hell-Gun-Capa-Debut-826x900.jpg\" alt=\"\" width=\"826\" height=\"900\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Hell-Gun-Capa-Debut-826x900.jpg 826w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Hell-Gun-Capa-Debut-768x837.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Hell-Gun-Capa-Debut-940x1024.jpg 940w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Hell-Gun-Capa-Debut.jpg 1175w\" sizes=\"auto, (max-width: 826px) 100vw, 826px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cercados de expectativas, o Hell Gun, do Paran\u00e1, est\u00e1 divulgando mais informa\u00e7\u00f5es sobre seu primeiro \u00e1lbum, \u201cKings of Beyond\u201d, que<\/p>\n","protected":false},"author":1,"featured_media":1470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[225,214,22],"class_list":["post-1681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-classic-metal-records","tag-hell-gun","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press\" \/>\n<meta property=\"og:description\" content=\"Cercados de expectativas, o Hell Gun, do Paran\u00e1, est\u00e1 divulgando mais informa\u00e7\u00f5es sobre seu primeiro \u00e1lbum, \u201cKings of Beyond\u201d, que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\" \/>\n<meta property=\"og:site_name\" content=\"Wargods Press\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-17T14:21:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa\",\"datePublished\":\"2020-04-17T14:21:44+00:00\",\"dateModified\":\"2020-04-17T14:21:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\"},\"wordCount\":619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"classic metal records\",\"Hell Gun\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\",\"name\":\"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2020-04-17T14:21:44+00:00\",\"dateModified\":\"2020-04-17T14:21:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"Wargods Press\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"Wargods Press\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"Wargods Press\"},\"image\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/","og_locale":"pt_BR","og_type":"article","og_title":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press","og_description":"Cercados de expectativas, o Hell Gun, do Paran\u00e1, est\u00e1 divulgando mais informa\u00e7\u00f5es sobre seu primeiro \u00e1lbum, \u201cKings of Beyond\u201d, que","og_url":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/","og_site_name":"Wargods Press","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2020-04-17T14:21:44+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/01\/Hell-Gun-Press2.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/"},"author":{"name":"WarGodsPress","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa","datePublished":"2020-04-17T14:21:44+00:00","dateModified":"2020-04-17T14:21:44+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/"},"wordCount":619,"commentCount":0,"publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["classic metal records","Hell Gun","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/","url":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/","name":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa - Wargods Press","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2020-04-17T14:21:44+00:00","dateModified":"2020-04-17T14:21:44+00:00","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/hell-gun-debut-sera-lancado-pela-classic-metal-records-confira-a-capa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Hell Gun: Debut ser\u00e1 lan\u00e7ado pela Classic Metal Records; confira a capa"}]},{"@type":"WebSite","@id":"https:\/\/wargodspress.com.br\/wargods\/#website","url":"https:\/\/wargodspress.com.br\/wargods\/","name":"Wargods Press","description":"Assessoria e Conte\u00fados","publisher":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/wargodspress.com.br\/wargods\/#organization","name":"Wargods Press","url":"https:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"Wargods Press"},"image":{"@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1681"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1681\/revisions"}],"predecessor-version":[{"id":1683,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1681\/revisions\/1683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/1470"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}