{"id":1181,"date":"2019-10-11T14:53:27","date_gmt":"2019-10-11T17:53:27","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1181"},"modified":"2019-10-11T14:53:27","modified_gmt":"2019-10-11T17:53:27","slug":"foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/","title":{"rendered":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-871\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Foxx-Press-2-900x596.jpg\" alt=\"\" width=\"900\" height=\"596\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Foxx-Press-2-900x596.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Foxx-Press-2-768x509.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Foxx-Press-2.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\u00a0<\/em><\/strong><\/p>\n<p>\u200bA vocalista <strong>F\u00d6XX SALEMA<\/strong> tem abordado temas pol\u00eamicos e atuais em suas letras, fugindo do lugar comum quando se trata de Heavy Metal. A tem\u00e1tica l\u00edrica do \u00e1lbum \u201cRebel Hearts\u201d reflete seus pensamentos de forma abrangente, indo da tem\u00e1tica LGBT+, passando por letras anti-su\u00edcidio, relacionamentos abusivos e tamb\u00e9m uma critica ao fundamentalismo religioso que tem se infiltrado na pol\u00edtica e sociedade brasileira. Este forte posicionamento tem trazido \u00e0 vocalista uma s\u00e9rie de ataques virtuais, mas tamb\u00e9m tem atingido pessoas que se identificam com essa proposta, tornando-a refer\u00eancia por letras de temas LGBT+ num pa\u00eds onde a intoler\u00e2ncia tem se intensificado.<\/p>\n<p><em>\u201cRebel Hearts\u201d<\/em>, a faixa-t\u00edtulo do \u00e1lbum, \u00e9 uma clara refer\u00eancia \u00e0 comunidade LGBT+, que agora no meio Heavy Metal sente-se representada por <strong>F\u00d6XX SALEMA<\/strong><strong>, <\/strong>pioneira quando se trata do assunto no Brasil.\u00a0 J\u00e1 a letra de <em>\u201cEmotional Rain\u201d<\/em> possui uma mensagem anti-suic\u00eddio<strong>, <\/strong>direcionada principalmente \u00e0s pessoas transg\u00eaneras, enquanto <em>\u201cVengeance Will Come\u201d<\/em> trata de relacionamentos abusivos\/trai\u00e7\u00e3o da confian\u00e7a. Outra faixa que se destaca \u00e9 <em>\u201cMankind\u201d<\/em>, uma verdadeira critica a corrup\u00e7\u00e3o, fundamentalismo religioso, pol\u00edtica e sociedade brasileira. No dia 31\/10 a m\u00fasica ganhar\u00e1 uma vers\u00e3o em formato de lyric video, celebrando um ano de seu lan\u00e7amento como single.<\/p>\n<p><strong><em>Confira as letras e demais detalhes sobre as m\u00fasicas aqui:<br \/>\n<\/em><\/strong><em><a href=\"http:\/\/bit.ly\/2M5shEH\">http:\/\/bit.ly\/2M5shEH<\/a><\/em><\/p>\n<p><em>\u00a0<\/em><em>\u201cRebel Hearts\u201d<\/em> continua recebendo diversas avalia\u00e7\u00f5es pela m\u00eddia especializada, e conforme a resenha de Marcelo Lopes Vieira, do site Gaveta de Bagun\u00e7as, \u201c<em>musicalmente temos, nestas oito composi\u00e7\u00f5es, uma abordagem vers\u00e1til e multifacetada dentro do hard rock\/heavy metal, inspirado pela escola norte-americana oitentista em suas formas mais cruas e tamb\u00e9m por alguns nomes do underground (tamb\u00e9m oitentista) da cena met\u00e1lica brit\u00e2nica, o que j\u00e1 era antecipado pelos singles de \u201cMankind\u201d e uma vers\u00e3o de \u201cConstant Fight\u201d, em 2013. As m\u00fasicas transitam pelas diversas maneiras de se explorar os classicismos do hard rock e do heavy metal, com guitarras vibrantes, variando bem melodia com crueza, o baixo pulsando em suporte \u00e0s harmonias, os refr\u00e3os e as linhas vocais bem desenhadas.\u201d. <\/em><\/p>\n<p><strong><em>Confira a resenha completa:<br \/>\n<\/em><\/strong><em><a href=\"https:\/\/gavetadebaguncas.com.br\/fox-salema-rebel-hearts\">https:\/\/gavetadebaguncas.com.br\/fox-salema-rebel-hearts<\/a><\/em><\/p>\n<p><strong><em>Ou\u00e7a \u201cRebel Hearts\u201d no Spotify:<\/em><\/strong><br \/>\n<a href=\"https:\/\/spoti.fi\/2KVPs4S\"><em>https:\/\/spoti.fi\/2KVPs4S<\/em><\/a><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Site:<\/strong> <a href=\"http:\/\/www.foxxsalemaband.com.br\">www.foxxsalemaband.com.br<\/a><br \/>\n<strong>Facebook:<\/strong> <a href=\"https:\/\/www.facebook.com\/foxxsalema78\">https:\/\/www.facebook.com\/foxxsalema78<\/a><br \/>\n<strong>Youtube:<\/strong> <a href=\"http:\/\/www.youtube.com\/user\/FoxxSalema\">www.youtube.com\/user\/FoxxSalema<\/a><br \/>\n<strong>Instagram:<\/strong> <a href=\"http:\/\/www.instagram.com\/foxxsalema\">www.instagram.com\/foxxsalema<\/a><br \/>\n<strong>Twitter:<\/strong> <a href=\"http:\/\/www.twitter.com\/foxxsalema\">www.twitter.com\/foxxsalema<\/a><br \/>\n<strong>Assessoria de Imprensa<\/strong>: <a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-832\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/F\u00f6xx-Salema-Capa.jpg\" alt=\"\" width=\"768\" height=\"768\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/F\u00f6xx-Salema-Capa.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/F\u00f6xx-Salema-Capa-600x600.jpg 600w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200bA vocalista F\u00d6XX SALEMA tem abordado temas pol\u00eamicos e atuais em suas letras, fugindo do lugar comum quando se<\/p>\n","protected":false},"author":1,"featured_media":1102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[148,22],"class_list":["post-1181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-foxx-salema","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u200bA vocalista F\u00d6XX SALEMA tem abordado temas pol\u00eamicos e atuais em suas letras, fugindo do lugar comum quando se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-11T17:53:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/09\/F\u00f6xx-Salema.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais\",\"datePublished\":\"2019-10-11T17:53:27+00:00\",\"dateModified\":\"2019-10-11T17:53:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Foxx Salema\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\",\"name\":\"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2019-10-11T17:53:27+00:00\",\"dateModified\":\"2019-10-11T17:53:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/","og_locale":"pt_BR","og_type":"article","og_title":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026","og_description":"\u00a0 \u200bA vocalista F\u00d6XX SALEMA tem abordado temas pol\u00eamicos e atuais em suas letras, fugindo do lugar comum quando se","og_url":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2019-10-11T17:53:27+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/09\/F\u00f6xx-Salema.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais","datePublished":"2019-10-11T17:53:27+00:00","dateModified":"2019-10-11T17:53:27+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Foxx Salema","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/","url":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/","name":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2019-10-11T17:53:27+00:00","dateModified":"2019-10-11T17:53:27+00:00","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/foxx-salema-tematica-lirica-do-album-aborda-temas-fortes-e-atuais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"F\u00f6xx Salema: Tem\u00e1tica l\u00edrica do \u00e1lbum aborda temas fortes e atuais"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1181"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1181\/revisions"}],"predecessor-version":[{"id":1182,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1181\/revisions\/1182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/1102"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}