{"id":1022,"date":"2019-08-27T11:42:24","date_gmt":"2019-08-27T14:42:24","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1022"},"modified":"2019-08-27T11:42:24","modified_gmt":"2019-08-27T14:42:24","slug":"michelly-show-confirmado-no-festival-das-rendas-em-sao-luis","status":"publish","type":"post","link":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/","title":{"rendered":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-863\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-900x618.jpg\" alt=\"\" width=\"566\" height=\"388\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-900x618.jpg 900w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-768x527.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg 1024w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><br \/>\n<\/strong>A banda de Hard Rock <strong>MICHELLY<\/strong>, uma das revela\u00e7\u00f5es do estilo na cidade de S\u00e3o Luis, Maranh\u00e3o, acaba de ser confirmada na segunda edi\u00e7\u00e3o do <em>Festival das Rendas<\/em>, que ser\u00e1 realizado no dia 7 de setembro pela Catirina Produ\u00e7\u00f5es. O <em>Festival das Rendas <\/em>foi um evento criado para celebrar a m\u00fasica, a economia criativa, o turismo e a gastronomia, como tamb\u00e9m valorizar o saber tradicional das rendeiras da regi\u00e3o. O mundo das rendeiras e a sua representatividade dentro da cultura maranhense s\u00e3o o grande mote do evento, que tamb\u00e9m prima pela diversidade e afeto na constru\u00e7\u00e3o de uma nova realidade.<\/p>\n<p>A segunda edi\u00e7\u00e3o ser\u00e1 realizado no Viva Raposa, conhecido como o cais do munic\u00edpio que fica h\u00e1 aproximadamente 28km de S\u00e3o Lu\u00eds. O festival tem como principais pilares: a economia criativa e est\u00edmulo \u00e0 produ\u00e7\u00e3o; o empreendedorismo feminino e a diversidade; a sustentabilidade e o respeito ao meio ambiente. Por ser realizado no feriado do Dia da Independ\u00eancia do Brasil, est\u00e3o sendo aguardados turistas que al\u00e9m de conhecer a tradicional renda de bilro, a gastronomia e as chamadas fronhas maranhenses, poder\u00e3o conhecer mais de perto a cena musical local e nacional.<\/p>\n<p>D\u00e3 Al Carneiro (vocal), Lucas Silva e Dayvisoon Trindade (guitarras) Lu\u00eds Eduardo (baixo) e Jo\u00e3o Victor Padilha (bateria) representar\u00e3o o som pesado e apresentar\u00e3o ao p\u00fablico m\u00fasicas de seu primeiro EP, <em>\u201cFreedom\u201d, <\/em>lan\u00e7ado digitalmente em todas as plataformas digitais no m\u00eas de junho e desde ent\u00e3o recebendo diversos coment\u00e1rios positivos tanto do p\u00fablico que acompanhou seu primeiro show no <em>Festival M\u00eas do Rock <\/em>quanto da imprensa. O vocalista D\u00e3 Al Carneiro comentou sobre o convite para o festival: <em>\u201cFicamos surpresos e muito felizes com o convite, pois tocar em um evento como esse far\u00e1 nosso som chegar a pessoas fora da cena Rock\/\/Metal, abrindo portas para mais oportunidades. O Festival das Rendas \u00e9 um evento muito interessante para a cultura local, e torcemos para que seja um sucesso! Contamos com a participa\u00e7\u00e3o do p\u00fablico em nosso show!\u201d. <\/em><\/p>\n<p><strong><em>Ou\u00e7a \u201cFreedom\u201d no Spotify:<br \/>\n<\/em><\/strong><a href=\"https:\/\/spoti.fi\/2GgVIAc\"><em>https:\/\/spoti.fi\/2GgVIAc<\/em><\/a><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/Michellyhardrock\">www.facebook.com\/Michellyhardrock<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/michellyhardrock\">www.instagram.com\/michellyhardrock<\/a><br \/>\n<strong>Twitter:<\/strong> <a href=\"http:\/\/www.twitter.com\/michellyhard\">www.twitter.com\/michellyhard<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1023\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/08\/Michelly-Show1-720x900.jpg\" alt=\"\" width=\"720\" height=\"900\" srcset=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/08\/Michelly-Show1-720x900.jpg 720w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/08\/Michelly-Show1-768x960.jpg 768w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/08\/Michelly-Show1-819x1024.jpg 819w, https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/08\/Michelly-Show1.jpg 1024w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A banda de Hard Rock MICHELLY, uma das revela\u00e7\u00f5es do estilo na cidade de S\u00e3o Luis, Maranh\u00e3o, acaba de ser<\/p>\n","protected":false},"author":1,"featured_media":863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[150,22],"class_list":["post-1022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-michelly","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"A banda de Hard Rock MICHELLY, uma das revela\u00e7\u00f5es do estilo na cidade de S\u00e3o Luis, Maranh\u00e3o, acaba de ser\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T14:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds\",\"datePublished\":\"2019-08-27T14:42:24+00:00\",\"dateModified\":\"2019-08-27T14:42:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Michelly\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\",\"name\":\"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2019-08-27T14:42:24+00:00\",\"dateModified\":\"2019-08-27T14:42:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/","og_locale":"pt_BR","og_type":"article","og_title":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026","og_description":"A banda de Hard Rock MICHELLY, uma das revela\u00e7\u00f5es do estilo na cidade de S\u00e3o Luis, Maranh\u00e3o, acaba de ser","og_url":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2019-08-27T14:42:24+00:00","og_image":[{"width":1024,"height":703,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds","datePublished":"2019-08-27T14:42:24+00:00","dateModified":"2019-08-27T14:42:24+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Michelly","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/","url":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/","name":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2019-08-27T14:42:24+00:00","dateModified":"2019-08-27T14:42:24+00:00","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/michelly-show-confirmado-no-festival-das-rendas-em-sao-luis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"MICHELLY: Show confirmado no Festival das Rendas em S\u00e3o Lu\u00eds"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"https:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1022"}],"version-history":[{"count":1,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1022\/revisions"}],"predecessor-version":[{"id":1024,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1022\/revisions\/1024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/863"}],"wp:attachment":[{"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}