{"id":862,"date":"2019-07-17T13:01:20","date_gmt":"2019-07-17T16:01:20","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=862"},"modified":"2019-07-17T13:01:20","modified_gmt":"2019-07-17T16:01:20","slug":"michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho","status":"publish","type":"post","link":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/","title":{"rendered":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-863\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-900x618.jpg\" alt=\"\" width=\"900\" height=\"618\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-900x618.jpg 900w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1-768x527.jpg 768w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/strong><\/p>\n<p>A <strong>MICHELLY<\/strong> \u00e9 uma banda de Hard Rock de S\u00e3o Lu\u00eds\/MA, formada no final de 2018 por Lucas Silva (guitarra) e D\u00e3 Al Carneiro (vocal) juntos com os integrantes Dayvisoon Trindade (guitarra) Lu\u00eds Eduardo (baixo) e Jo\u00e3o Victor Padilha (bateria). Com a forma\u00e7\u00e3o fechada, iniciaram-se os trabalhos de concep\u00e7\u00e3o musical e visual calcados no Hard Rock dos anos 80, mas com um p\u00e9 na atualidade. E foi justamente buscando influ\u00eancias naquela d\u00e9cada de ouro que o quinteto modelou sua sonoridade: <em>\u201cAinda muito jovens, sofr\u00edamos grande influ\u00eancia ao ouvir grandes bandas, como Guns \u2018n\u2019 Roses, M\u00f6tley Crue, bem como algumas que fizeram sucesso nos anos 70, como Led Zeppelin e Aerosmith. Diria que \u00e9 algo que j\u00e1 est\u00e1 enraizado. A tem\u00e1tica e sonoridade dessas bandas representam bem nossos pensamentos e sentimentos, ent\u00e3o nossas m\u00fasicas j\u00e1 nasceram com o estilo, mesmo que n\u00e3o o escolh\u00eassemos.\u201d.<\/em><\/p>\n<p>S\u00e3o Lu\u00eds n\u00e3o \u00e9 apenas a capital do Maranh\u00e3o, mas tamb\u00e9m de uma forte cena Rock\/Metal. A <strong>MICHELLY<\/strong> est\u00e1 amplamente inserida neste meio, que nos \u00faltimos anos revelou bandas como JackDevil, F\u00faria Louca, School Thrash, Alchimist e tantos outros nomes. Para os integrantes, participar de tal movimento do som pesado maranhense \u00e9 motivo de grande orgulho: <em>\u201cAs bandas citadas nos influenciam muito, nos fazem acreditar que \u00e9 poss\u00edvel fazer Rock num estado onde o estilo era t\u00e3o escasso at\u00e9 um passado recente. Esperamos muito em breve fazer parte dessa cena que j\u00e1 \u00e9 destaque nacionalmente com suas constantes revela\u00e7\u00f5es e, mais ainda, pretendemos assim como essas bandas levar o nome do Maranh\u00e3o pra fora.\u201d.<\/em><\/p>\n<p>A banda foi formada h\u00e1 pouco mais de meio ano e j\u00e1 est\u00e1 com shows agendados, um EP lan\u00e7ado e o trabalho n\u00e3o para. Para lidar com tanto trabalho, \u00e9 preciso de muita organiza\u00e7\u00e3o e vontade de crescer. Mas \u00e9 preciso mais alguns ingredientes: <em>\u201ccom certeza \u00e9 necess\u00e1rio foco, unidade e trabalho duro, o segredo tamb\u00e9m \u00e9 sempre acreditar que se pode fazer o melhor mesmo sem condi\u00e7\u00f5es de fazer, acreditamos que qualquer um \u00e9 capaz s\u00f3 \u00e9 preciso fazer de verdade e esse trabalho \u00e9 a tradu\u00e7\u00e3o do esfor\u00e7o de todos os integrantes, cada um contribuindo da sua maneira para a realiza\u00e7\u00e3o de um sonho coletivo\u201d. <\/em>E seguindo a agenda de divulga\u00e7\u00e3o do EP, a banda tocar\u00e1 neste s\u00e1bado, 20\/07, no Fanzine Rock Bar em S\u00e3o Luis, em evento comemorativo ao Dia Mundial do Rock, ao lado das bandas Brutalian, Gallo Azhuu, SavageZ, Serial Killer e Velttenz, com in\u00edcio programado para as 18h.<\/p>\n<p><strong><em>Saiba mais:<br \/>\n<\/em><\/strong><a href=\"https:\/\/www.facebook.com\/events\/1068877860168510\/\"><em>https:\/\/www.facebook.com\/events\/1068877860168510\/<\/em><\/a><\/p>\n<p>O vocalista D\u00e3 Al Carneiro tamb\u00e9m faz parte do Alchimist (como baterista), que toca um som diferente do <strong>MICHELLY<\/strong>. Mas n\u00e3o \u00e9 apenas D\u00e3 que tem jornada dupla: <em>\u201cN\u00e3o \u00e9 uma tarefa t\u00e3o dif\u00edcil, pois no Alchimist a fun\u00e7\u00e3o \u00e9 de tocar bateria e na Michelly a outra metade de um prazer que se concretizar, ou seja, cantar. Tudo culmina em uma satisfa\u00e7\u00e3o quase indescrit\u00edvel por serem estilos que amo, e desempenhando tamb\u00e9m pap\u00e9is que amo. O guitarrista Dayvison Trindade toca em uma banda chamada Em\u00eddio. Nosso baterista j\u00e1 \u00e9 velho conhecido da cena maranhense e comp\u00f4s diversas bandas, em seu mais recente trabalho antes de se unir a n\u00f3s foi com a banda Black Jack Romeo.\u201d. <\/em><\/p>\n<p>Atualmente a banda divulga sem rec\u00e9m-lan\u00e7ado primeiro EP, chamado <em>\u201cFreedom\u201d<\/em>, com cinco faixas <em>(\u201cHey Baby\u201d, \u201cMaster\u201d, \u201cFreedom\u201d, \u201cFly Back to Home\u201d <\/em>e<em> \u201cNever End\u201d<\/em>). A grava\u00e7\u00e3o foi feita no Est\u00fadio Garagem com produ\u00e7\u00e3o de D\u00e3 Carneiro, enquanto a capa \u00e9 uma arte criada pelo artista gr\u00e1fico Eron Ara\u00fajo e os v\u00eddeos foram criados por Dayisson Trindade. Foram poucos, mas intensos meses de trabalho, mas o resultado final \u00e9 compensador. A banda explica alguns detalhes do processo: <em>\u201ctrabalhar nas m\u00fasicas foi uma grande surpresa, pois n\u00e3o acredit\u00e1vamos que saber\u00edamos compor. A maioria das m\u00fasicas foi escrita por D\u00e3 Carneiro e Lucas Silva e foi incr\u00edvel acompanhar esse processo de forma\u00e7\u00e3o trecho por trecho. Encontramos dificuldade com algumas limita\u00e7\u00f5es e falta de experi\u00eancia, tais como a pronuncia do ingl\u00eas, e por sorte pudemos contar com nossos Amigos Luciano Warren, C\u00e1ssio Marcos e Kayla Sussana, aos quais nutrimos profunda gratid\u00e3o.\u201d.<\/em><\/p>\n<p><strong><em>Ou\u00e7a \u201cFreedom\u201d no Spotify:<br \/>\n<\/em><\/strong><a href=\"https:\/\/spoti.fi\/2GgVIAc\"><em>https:\/\/spoti.fi\/2GgVIAc<\/em><\/a><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/Michellyhardrock\">www.facebook.com\/Michellyhardrock<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/michellyhardrock\">www.instagram.com\/michellyhardrock<\/a><br \/>\n<strong>Twitter:<\/strong> <a href=\"http:\/\/www.twitter.com\/michellyhard\">www.twitter.com\/michellyhard<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-864\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Capa.jpg\" alt=\"\" width=\"778\" height=\"768\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Capa.jpg 778w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Capa-768x758.jpg 768w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A MICHELLY \u00e9 uma banda de Hard Rock de S\u00e3o Lu\u00eds\/MA, formada no final de 2018 por Lucas Silva (guitarra)<\/p>\n","protected":false},"author":1,"featured_media":863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[150,22],"class_list":["post-862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-michelly","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"A MICHELLY \u00e9 uma banda de Hard Rock de S\u00e3o Lu\u00eds\/MA, formada no final de 2018 por Lucas Silva (guitarra)\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-17T16:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho\",\"datePublished\":\"2019-07-17T16:01:20+00:00\",\"dateModified\":\"2019-07-17T16:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\"},\"wordCount\":776,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Michelly\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\",\"name\":\"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2019-07-17T16:01:20+00:00\",\"dateModified\":\"2019-07-17T16:01:20+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/","og_locale":"pt_BR","og_type":"article","og_title":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026","og_description":"A MICHELLY \u00e9 uma banda de Hard Rock de S\u00e3o Lu\u00eds\/MA, formada no final de 2018 por Lucas Silva (guitarra)","og_url":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2019-07-17T16:01:20+00:00","og_image":[{"width":1024,"height":703,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/07\/Michelly-Press1.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho","datePublished":"2019-07-17T16:01:20+00:00","dateModified":"2019-07-17T16:01:20+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/"},"wordCount":776,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Michelly","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/","url":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/","name":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2019-07-17T16:01:20+00:00","dateModified":"2019-07-17T16:01:20+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/michelly-trabalhando-em-conjunto-para-a-realizacao-de-um-sonho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Michelly: Trabalhando em conjunto para a realiza\u00e7\u00e3o de um sonho"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":1,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/862\/revisions"}],"predecessor-version":[{"id":865,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/862\/revisions\/865"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/863"}],"wp:attachment":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=862"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}