{"id":6208,"date":"2025-07-17T21:51:00","date_gmt":"2025-07-18T00:51:00","guid":{"rendered":"https:\/\/wargodspress.com.br\/wargods\/?p=6208"},"modified":"2025-07-17T21:52:32","modified_gmt":"2025-07-18T00:52:32","slug":"deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep","status":"publish","type":"post","link":"http:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/","title":{"rendered":"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP"},"content":{"rendered":"\n<p>A veterana banda caxiense <strong>Deadly<\/strong> <strong>Shadows<\/strong> se apresenta em Porto Alegre no dia 16 de agosto, no <strong>Gravador Pub<\/strong>, como parte da programa\u00e7\u00e3o do evento de lan\u00e7amento do novo EP da banda <strong>Distraught<\/strong>, <strong><em>\u201cInVolution\u201d<\/em><\/strong>. O evento ainda conta com a participa\u00e7\u00e3o da banda <strong>Vulgar Tribute of Power<\/strong>, tributo ao <strong>Pantera<\/strong>, de Florian\u00f3polis. A abertura da casa est\u00e1 marcada para 18h, com ingressos dispon\u00edveis pela plataforma Sympla.<\/p>\n\n\n\n<p>Ap\u00f3s retornar oficialmente em 2022, o <strong>Deadly<\/strong> <strong>Shadows<\/strong> lan\u00e7ou seu primeiro \u00e1lbum completo, <strong><em>\u201cRunning Back in Time\u201d<\/em><\/strong>, em mar\u00e7o de 2024. O disco apresenta uma combina\u00e7\u00e3o de faixas in\u00e9ditas e regrava\u00e7\u00f5es de composi\u00e7\u00f5es cl\u00e1ssicas da banda, resgatando sua identidade com um som calcado no Heavy Metal tradicional, por\u00e9m enriquecido por nuances bluesy. A produ\u00e7\u00e3o ficou por conta de <strong>Thiago<\/strong> <strong>Caurio<\/strong>, no <strong>Black<\/strong> <strong>Stork<\/strong> <strong>Studio<\/strong>, em Caxias do Sul, com masteriza\u00e7\u00e3o de <strong>Benhur<\/strong> <strong>Lima<\/strong> e arte gr\u00e1fica assinada por <strong>Maur\u00edcio<\/strong> <strong>Grezzana<\/strong>, guitarrista da banda.<\/p>\n\n\n\n<p>Paralelamente \u00e0 agenda de shows, o <strong>Deadly Shadows<\/strong> est\u00e1 finalizando as grava\u00e7\u00f5es de um novo EP com quatro faixas in\u00e9ditas, novamente sob produ\u00e7\u00e3o de <strong>Thiago<\/strong> <strong>Caurio<\/strong> no est\u00fadio <strong>Black<\/strong> <strong>Stork<\/strong>. Os instrumentos j\u00e1 foram registrados e a banda se encontra agora na etapa final, captando os vocais. O material ser\u00e1 lan\u00e7ado ainda em 2025 e promete manter o clima direto, mel\u00f3dico e pesado que caracteriza a atual fase do grupo, que \u00e9 composto por <strong>Tony<\/strong> <strong>Devil<\/strong> (vocal), <strong>Maur\u00edcio<\/strong> <strong>Grezzana<\/strong> e <strong>J\u00falio<\/strong> <strong>Machado<\/strong> (guitarras), <strong>Davi<\/strong> <strong>Frezza<\/strong> (baixo) e <strong>Daniel<\/strong> <strong>Balconi<\/strong> (bateria).<\/p>\n\n\n\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n\n\n\n<p><strong>Evento: <\/strong>Lan\u00e7amento do EP <strong><em>\u201cInVolution\u201d<\/em><\/strong> (Distraught)<br><strong>Data:<\/strong> S\u00e1bado, 16 de agosto<br><strong>Hor\u00e1rio:<\/strong> 18h<br><strong>Local:<\/strong> Gravador Pub \u2013 Rua Ernesto da Fontoura, 962 \u2013 Porto Alegre\/RS<br><strong>Atra\u00e7\u00f5es:<\/strong> Distraught, Deadly Shadows, Vulgar Tribute of Power<br><strong>Ingressos dispon\u00edveis via Sympla:<\/strong><br><a href=\"https:\/\/www.sympla.com.br\/evento\/distraught-show-de-lancamento-involution\/3032784?\">https:\/\/www.sympla.com.br\/evento\/distraught-show-de-lancamento-involution\/3032784?<\/a><\/p>\n\n\n\n<p><strong><em>Assista ao v\u00eddeo clipe de \u201cRunning Back in Time\u201d:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Deadly Shadows - Running Back in Time (Official Music Video)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/lR2LnoTdQ3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Ou\u00e7a o \u00e1lbum \u201cRunning Back in Time\u201d no Spotify:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Running Back in Time\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/671u14Wv6LnUpoj5ypvhmt?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Cr\u00e9ditos da foto: <\/strong>&nbsp;Gabriel Frezza<\/p>\n\n\n\n<p><strong>Contatos:<\/strong><br><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/deadlyshadowsofficial\">www.facebook.com\/deadlyshadowsofficial<\/a><br><a href=\"http:\/\/www.facebook.com\/thunderforcehm\"><\/a><strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/deadlyshadows_official\">www.instagram.com\/deadlyshadows_official<\/a><a href=\"http:\/\/www.instagram.com\/thunderforce\"><\/a><br><strong>YouTube: <\/strong><a href=\"http:\/\/www.youtube.com\/@deadlyshadows_official\">www.youtube.com\/@deadlyshadows_official<\/a><br><strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA-1024x1024.jpg\" alt=\"\" class=\"wp-image-6209\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA-1024x1024.jpg 1024w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA-900x900.jpg 900w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA-600x600.jpg 600w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA-768x768.jpg 768w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2025\/07\/Deadly-Shadows-Show-POA.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A veterana banda caxiense Deadly Shadows se apresenta em Porto Alegre no dia 16 de agosto, no Gravador Pub, como<\/p>\n","protected":false},"author":1,"featured_media":5487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[590,3],"tags":[22],"class_list":["post-6208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-news","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"description\" content=\"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\" \/>\n<meta property=\"og:description\" content=\"A veterana banda caxiense Deadly Shadows se apresenta em Porto Alegre no dia 16 de agosto, no Gravador Pub, como parte da programa\u00e7\u00e3o do evento de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T00:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T00:52:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2024\/04\/Deadly-Shadows-Press1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1564\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\" \/>\n<meta name=\"twitter:description\" content=\"A veterana banda caxiense Deadly Shadows se apresenta em Porto Alegre no dia 16 de agosto, no Gravador Pub, como parte da programa\u00e7\u00e3o do evento de\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2024\/04\/Deadly-Shadows-Press1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\",\"datePublished\":\"2025-07-18T00:51:00+00:00\",\"dateModified\":\"2025-07-18T00:52:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\"},\"wordCount\":385,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Wargods Press\"],\"articleSection\":[\"Agenda\",\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\",\"name\":\"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2025-07-18T00:51:00+00:00\",\"dateModified\":\"2025-07-18T00:52:32+00:00\",\"description\":\"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP - WARGODS PRESS - 2006 - 2026","description":"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/","og_locale":"pt_BR","og_type":"article","og_title":"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP","og_description":"A veterana banda caxiense Deadly Shadows se apresenta em Porto Alegre no dia 16 de agosto, no Gravador Pub, como parte da programa\u00e7\u00e3o do evento de","og_url":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2025-07-18T00:51:00+00:00","article_modified_time":"2025-07-18T00:52:32+00:00","og_image":[{"width":1564,"height":1040,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2024\/04\/Deadly-Shadows-Press1.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_title":"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP","twitter_description":"A veterana banda caxiense Deadly Shadows se apresenta em Porto Alegre no dia 16 de agosto, no Gravador Pub, como parte da programa\u00e7\u00e3o do evento de","twitter_image":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2024\/04\/Deadly-Shadows-Press1.jpg","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP","datePublished":"2025-07-18T00:51:00+00:00","dateModified":"2025-07-18T00:52:32+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/"},"wordCount":385,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Wargods Press"],"articleSection":["Agenda","News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/","url":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/","name":"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2025-07-18T00:51:00+00:00","dateModified":"2025-07-18T00:52:32+00:00","description":"WARGODS PRESS - 2006 - 2026 - Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/deadly-shadows-anuncia-show-em-porto-alegre-em-agosto-e-novidades-sobre-novo-ep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Deadly Shadows anuncia show em Porto Alegre em agosto e novidades sobre novo EP"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=6208"}],"version-history":[{"count":2,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6208\/revisions"}],"predecessor-version":[{"id":6211,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/6208\/revisions\/6211"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/5487"}],"wp:attachment":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=6208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=6208"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=6208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}