{"id":2098,"date":"2020-08-26T16:12:21","date_gmt":"2020-08-26T19:12:21","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=2098"},"modified":"2020-08-26T16:36:54","modified_gmt":"2020-08-26T19:36:54","slug":"metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom","status":"publish","type":"post","link":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/","title":{"rendered":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2099\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/The-Troops-of-Doom-Metal-Legacy.jpg\" alt=\"\" width=\"730\" height=\"523\" \/><\/p>\n<p>O novo epis\u00f3dio do podcast <strong>METAL LEGACY<\/strong> traz uma entrevista com o guitarrista Jairo \u201cTormentor\u201d Guedz, m\u00fasico mineiro que iniciou sua carreira sendo um dos fundadores do Sepultura e que depois fez hist\u00f3ria com o The Mist. Al\u00e9m disso, Jairo trabalhou com os conterr\u00e2neos do Eminence e do Overdose, al\u00e9m de criar diversos projetos no decorrer dos anos, como o The Southern Blacklist e o Metallica Cover Brazil. Seus talentos tamb\u00e9m est\u00e3o ligados ao mundo da arte, onde ganhou destaque ao trabalhar numa confec\u00e7\u00e3o minuciosa de miniaturas baseadas na Segunda Guerra Mundial, incluindo cen\u00e1rios. Atualmente o guitarrista tamb\u00e9m se dedicado \u00e0 sua grife United Satans of America, que ser\u00e1 lan\u00e7ada em breve. No bate-papo, Jairo contou alguns detalhes acerca do The Mist, desde a influ\u00eancia de Industrial nos \u00e1lbuns da d\u00e9cada de 1990 at\u00e9 seu retorno bem sucedido. Lembran\u00e7as de sua passagem pelo Overdose e Eminence tamb\u00e9m foram abordadas, como o caso em que quase se tornou membro do Ministry a convite de Al Jourgensen ap\u00f3s sua ida aos EUA para gravar <em>\u201cHumanology\u201d<\/em> (Eminence, 2004).<\/p>\n<p>Sobre o The Troops of Doom, Jairo explicou em detalhes o surgimento da banda, contando que a ideia j\u00e1 teria sido trabalhada h\u00e1 quatro anos, e com o in\u00edcio da pandemia as coisas come\u00e7aram a tomar forma. Com o EP <em>&#8220;The Rise of Heresy&#8221;<\/em> prestes a ser lan\u00e7ado, o The Troops of Doom j\u00e1 colhe uma boa repercuss\u00e3o com o primeiro single, <em>\u201cBetween the Devil and the Deep Blue Sea\u201d, <\/em>e j\u00e1 planeja um novo single para o m\u00eas de setembro. Sua rela\u00e7\u00e3o com os integrantes e ex-integrantes do Sepultura tamb\u00e9m veio \u00e0 tona na entrevista, com Jairo destacando a rela\u00e7\u00e3o de respeito com Max, Iggor, Paulo e Andreas, dizendo ainda que entrou em contato com todos antes de lan\u00e7ar o projeto, n\u00e3o pedindo um aval jur\u00eddico se poderia avan\u00e7ar com a banda, j\u00e1 que ele \u00e9 compositor de m\u00fasicas do <em>\u201cBestial Devastation\u201d<\/em> e <em>\u201cMorbid Visions\u201d<\/em> e det\u00e9m o direito de us\u00e1-las, mas sim um aval dos antigos companheiros de banda, uma esp\u00e9cie de \u201cben\u00e7\u00e3o\u201d e apoio moral de quem ajudou a escrever a hist\u00f3ria do Metal nacional juntos. O The Troops of Doom conta ainda com Alex Kafer (vocal e baixo), Marcelo Vasco (guitarra) e Alexandre Oliveira (bateria). Confira mais detalhes acessando o podcast no Spotify, Deezer, Google Podcasts ou Anchor.<\/p>\n<p><strong><em>Ou\u00e7a o podcast no Spotify:<\/em><\/strong><\/p>\n<p><iframe style=\"border-radius: 12px\" width=\"100%\" height=\"152\" title=\"Spotify Embed: Metal Legacy - Epis\u00f3dio III - Entrevista com Jairo Guedz do The Troopers of Doom\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/3Mij5rOpwJ7D62fpDoAT99?utm_source=oembed\"><\/iframe><\/p>\n<p><strong><em>Ou\u00e7a o podcast no Anchor:<br \/>\n<\/em><\/strong><a href=\"https:\/\/anchor.fm\/metallegacy\"><em>https:\/\/anchor.fm\/metallegacy<\/em><\/a><\/p>\n<p><strong><em>Ou\u00e7a o podcast no Deezer:<br \/>\n<\/em><\/strong><a href=\"https:\/\/www.deezer.com\/br\/show\/1458152\"><em>https:\/\/www.deezer.com\/br\/show\/1458152<\/em><\/a><\/p>\n<p><strong><em>Google Podcasts:<br \/>\n<\/em><\/strong><a href=\"https:\/\/bit.ly\/MetalLegacyGoogle\"><em>https:\/\/bit.ly\/MetalLegacyGoogle<\/em><\/a><\/p>\n<p>Apresentado por Maicon Leite e Vicente de Albuquerque Maranh\u00e3o, o <strong>METAL LEGACY <\/strong>ter\u00e1 como caracter\u00edstica entrevistar pessoas ligadas ao Heavy Metal, seja m\u00fasicos, produtores, jornalistas e at\u00e9 mesmo profissionais de outras \u00e1reas, mas que possuam v\u00ednculo com som pesado. Al\u00e9m disso, est\u00e3o previstos epis\u00f3dios tem\u00e1ticos e drops entre um epis\u00f3dio e outro. Para as bandas que quiserem enviar material para an\u00e1lise, basta entrar em contato atrav\u00e9s do e-mail <a href=\"mailto:metallegacypodcast@gmail.com\">metallegacypodcast@gmail.com<\/a>. Em nosso Instagram tamb\u00e9m disponibilizamos dicas di\u00e1rias de \u00e1lbuns, singles e EPs, destacando registros de todas as \u00e9pocas, estilos e formatos. Para os interessados em conferir estas dicas, basta seguir nossa playlist no Spotify, disponibilizada abaixo.<\/p>\n<p><strong><em>Playlist \u201cMetal Legacy \u2013 Indica\u00e7\u00f5es\u201d:<br \/>\n<\/em><\/strong><\/p>\n<p><iframe style=\"border-radius: 12px\" width=\"100%\" height=\"380\" title=\"Spotify Embed: Metal Legacy - Indica\u00e7\u00f5es\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/playlist\/2vk9b09qt1ybkYpKUpGCRr?utm_source=oembed\"><\/iframe><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/MetalLegacyPodcast\">www.facebook.com\/MetalLegacyPodcast<\/a><br \/>\n<strong>Instagram: <\/strong><a href=\"http:\/\/www.instagram.com\/metallegacypodcast\">www.instagram.com\/metallegacypodcast<\/a><br \/>\n<strong>Assessoria de Imprensa:<\/strong> <a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2100\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz-900x900.png\" alt=\"\" width=\"900\" height=\"900\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz-900x900.png 900w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz-600x600.png 600w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz-768x768.png 768w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz-1024x1024.png 1024w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/3-Jairo-Guedz.png 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo epis\u00f3dio do podcast METAL LEGACY traz uma entrevista com o guitarrista Jairo \u201cTormentor\u201d Guedz, m\u00fasico mineiro que iniciou<\/p>\n","protected":false},"author":1,"featured_media":2099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[281,3,282],"tags":[284,283,286,22],"class_list":["post-2098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metal-legacy","category-news","category-podcast","tag-metal-legacy","tag-metal-legacy-podcast","tag-the-troops-of-doom","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"O novo epis\u00f3dio do podcast METAL LEGACY traz uma entrevista com o guitarrista Jairo \u201cTormentor\u201d Guedz, m\u00fasico mineiro que iniciou\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T19:12:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-26T19:36:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/The-Troops-of-Doom-Metal-Legacy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom\",\"datePublished\":\"2020-08-26T19:12:21+00:00\",\"dateModified\":\"2020-08-26T19:36:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"metal legacy\",\"metal legacy podcast\",\"the troops of doom\",\"Wargods Press\"],\"articleSection\":[\"Metal Legacy\",\"News\",\"Podcast\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\",\"name\":\"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2020-08-26T19:12:21+00:00\",\"dateModified\":\"2020-08-26T19:36:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/","og_locale":"pt_BR","og_type":"article","og_title":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026","og_description":"O novo epis\u00f3dio do podcast METAL LEGACY traz uma entrevista com o guitarrista Jairo \u201cTormentor\u201d Guedz, m\u00fasico mineiro que iniciou","og_url":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2020-08-26T19:12:21+00:00","article_modified_time":"2020-08-26T19:36:54+00:00","og_image":[{"width":730,"height":523,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/08\/The-Troops-of-Doom-Metal-Legacy.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom","datePublished":"2020-08-26T19:12:21+00:00","dateModified":"2020-08-26T19:36:54+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["metal legacy","metal legacy podcast","the troops of doom","Wargods Press"],"articleSection":["Metal Legacy","News","Podcast"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/","url":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/","name":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2020-08-26T19:12:21+00:00","dateModified":"2020-08-26T19:36:54+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/metal-legacy-jairo-tormentor-guedz-revela-fatos-ineditos-da-carreira-e-detalhes-sobre-o-the-troops-of-doom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Metal Legacy: Jairo \u201cTormentor\u201d Guedz revela fatos in\u00e9ditos da carreira e detalhes sobre o The Troops of Doom"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=2098"}],"version-history":[{"count":3,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2098\/revisions"}],"predecessor-version":[{"id":2103,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/2098\/revisions\/2103"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/2099"}],"wp:attachment":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=2098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=2098"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=2098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}