{"id":1695,"date":"2020-04-21T10:59:48","date_gmt":"2020-04-21T13:59:48","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1695"},"modified":"2020-04-21T11:02:39","modified_gmt":"2020-04-21T14:02:39","slug":"a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative","status":"publish","type":"post","link":"http:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/","title":{"rendered":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1696\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1-900x600.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1-900x600.jpg 900w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1-768x512.jpg 768w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>A banda ga\u00facha de Dark Metal <strong>A Sorrowful Dream<\/strong> est\u00e1 divulgando um v\u00eddeo ao vivo de <em>\u201cLove You to Death\u201d<\/em> em homenagem ao baixista\/vocalista Peter Steele, do Type O Negative, falecido h\u00e1 dez anos devido a um aneurisma a\u00f3rtico. O gigante nova-iorquino construiu uma carreira de sucesso a partir de seu trabalho ca\u00f3tico com a banda Carnivore, na d\u00e9cada de 1980. Entretanto, foi com o som pesad\u00edssimo e sorumb\u00e1tico criado com o Type O Negative que sua carreira teve um salto enorme, marcando principalmente a d\u00e9cada de 1990 com cl\u00e1ssicos como <em>\u201cBloody Kisses\u201d <\/em>(1993) e <em>\u201cOctober Rust\u201d<\/em> (1996). Para o vocalista \u00c9der Macedo, a descoberta da banda foi fundamental para sua forma\u00e7\u00e3o musical: <em>\u201cMinha vida mudou quando ouvi o \u201cBloody Kisses\u201d. Comprei o vinil, que, com orgulho, tenho at\u00e9 hoje. Aquela m\u00fasica se mostrou como algo poss\u00edvel: a cad\u00eancia, o timbre e a afia\u00e7\u00e3o das guitarras e o vocal&#8230; sem d\u00favida o vocal do Peter. \u00c9 o tipo de banda que te faz querer ter uma banda e foi assim para n\u00f3s. Reformulamos o que entend\u00edamos como m\u00fasica: como assim? tem Punk, tem Doom, tem g\u00f3tico, tem at\u00e9 sarcasmo&#8230;\u201d.<\/em><em>\u00a0<\/em><\/p>\n<p><strong><em>Assista ao cover:<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/t_vxaPuz-k4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><em>\u00a0<\/em>O v\u00eddeo foi gravado no Teatro do CIEE (Porto Alegre), em outubro de 2015, no show de lan\u00e7amento do \u00e1lbum <em>\u201cPassion\u201d<\/em>. Foi a primeira vez que a <strong>A Sorrowful Dream <\/strong>executou o cover de <em>\u201cLove You to Death\u201d<\/em> ao vivo, tendo anteriormente j\u00e1 tocado <em>\u201cChristian Woman\u201d <\/em>e <em>\u201cSummer Breeze\u201d<\/em>. Entretanto, o vocalista relembra um fato curioso: <em>\u201c\u201dSummer Breeze\u201d foi o primeiro cover da banda. Tocamos em 96 quando ainda nem t\u00ednhamos baterista. Est\u00e1vamos \u201cengatinhando\u201d, aprendendo. O Type O Negative foi influ\u00eancia para 10 em cada 10 bandas voltadas ao nosso estilo, ent\u00e3o imagina um bando de moleques ga\u00fachos em uma garagem vibrando a cada acorde tocado&#8230;\u201d. \u201cSummer Breeze\u201d, <\/em>ali\u00e1s, \u00e9 um cover que o pr\u00f3prio Type O Negative gravou, j\u00e1 que a m\u00fasica original \u00e9 da dupla norte-americana Seals &amp; Crofts, formada por Jim Seals (guitarra, saxofone e violino) e Dash Crofts (bateria, mandolim e teclado).<\/p>\n<p>Com o falecimento de Peter em abril de 2010, o mundo perdia um m\u00fasico \u00fanico, que al\u00e9m de talentoso, vivia em seus pr\u00f3prios termos. \u00c9der Macedo lamenta: <em>&#8220;Sem d\u00favida Peter Steele faz muita falta na m\u00fasica. E certamente ele ainda estaria, como muitos ainda est\u00e3o, fazendo m\u00fasica boa e original, e que n\u00e3o se rende a modismos ou tend\u00eancias. Fazer arte porque tem que fazer arte, porque tem que superar o senso comum e fazer com que adolescentes, como \u00e9ramos, tenham seu mundo transformado. Pois \u00e9 isso que queremos!\u201d.<\/em><\/p>\n<p>\u00c9der Macedo (vocal), Josie Demeneghi (vocal), Geovane &#8220;Tuko&#8221; Lacerda (baixo), Mari Vieira (teclados), Aur\u00e9lio Martins (guitarra), Lucas Vargas (guitarra\/violinos) e Marcelo Dornel (bateria) tem aproveitado a quarentena\/isolamento devido \u00e0 pandemia para compor seu terceiro \u00e1lbum. Formada em 1996, a <strong>A Sorrowful Dream <\/strong>soube mesclar suas diversas influ\u00eancias e moldar uma sonoridade \u00fanica, incluindo elementos de Death Metal, Doom Metal, Heavy Metal e m\u00fasica erudita de forma impar, presente em suas diversas demos, singles, e nos \u00e1lbuns <em>\u201cToward Nothingness\u201d<\/em> (2009) e <em>\u201cPassion\u201d<\/em> (2015), ambos dispon\u00edveis em todas as plataformas digitais.<\/p>\n<p><strong><em>Assista ao v\u00eddeo clipe de \u201cPassion\u201d:<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Lm_J8KjGcJM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/em><\/strong><\/p>\n<p><strong>Contatos:<\/strong><br \/>\n<strong>Site oficial:<\/strong> <a href=\"http:\/\/www.asorrowfuldream.com\">www.asorrowfuldream.com<\/a><br \/>\n<strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/asorrowfuldream\">www.facebook.com\/asorrowfuldream<\/a><br \/>\n<strong>Twitter:<\/strong> <a href=\"http:\/\/www.twitter.com\/asorrowfuldream\">www.twitter.com\/asorrowfuldream<\/a><br \/>\n<strong>Instagram:<\/strong>\u00a0 <a href=\"http:\/\/www.instagram.com\/asorrowfuldream\">www.instagram.com\/asorrowfuldream<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1697\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Cover.jpeg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Cover.jpeg 640w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/Cover-600x600.jpeg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A banda ga\u00facha de Dark Metal A Sorrowful Dream est\u00e1 divulgando um v\u00eddeo ao vivo de \u201cLove You to Death\u201d<\/p>\n","protected":false},"author":1,"featured_media":1696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[155,22],"class_list":["post-1695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-a-sorrowful-dream","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"A banda ga\u00facha de Dark Metal A Sorrowful Dream est\u00e1 divulgando um v\u00eddeo ao vivo de \u201cLove You to Death\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T13:59:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-21T14:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative\",\"datePublished\":\"2020-04-21T13:59:48+00:00\",\"dateModified\":\"2020-04-21T14:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\"},\"wordCount\":596,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"A Sorrowful Dream\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\",\"url\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\",\"name\":\"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2020-04-21T13:59:48+00:00\",\"dateModified\":\"2020-04-21T14:02:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/","og_locale":"pt_BR","og_type":"article","og_title":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026","og_description":"A banda ga\u00facha de Dark Metal A Sorrowful Dream est\u00e1 divulgando um v\u00eddeo ao vivo de \u201cLove You to Death\u201d","og_url":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2020-04-21T13:59:48+00:00","article_modified_time":"2020-04-21T14:02:39+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2020\/04\/ASD-Press1.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#article","isPartOf":{"@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative","datePublished":"2020-04-21T13:59:48+00:00","dateModified":"2020-04-21T14:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/"},"wordCount":596,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["A Sorrowful Dream","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/","url":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/","name":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2020-04-21T13:59:48+00:00","dateModified":"2020-04-21T14:02:39+00:00","breadcrumb":{"@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wargodspress.com.br\/wargods\/a-sorrowful-dream-confira-video-ao-vivo-em-homenagem-a-peter-steele-do-type-o-negative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"A Sorrowful Dream: Confira v\u00eddeo ao vivo em homenagem a Peter Steele, do Type O Negative"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1695"}],"version-history":[{"count":1,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1695\/revisions"}],"predecessor-version":[{"id":1698,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1695\/revisions\/1698"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/1696"}],"wp:attachment":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1695"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}