{"id":1425,"date":"2020-01-08T18:30:30","date_gmt":"2020-01-08T20:30:30","guid":{"rendered":"http:\/\/wargodspress.com.br\/wargods\/?p=1425"},"modified":"2020-01-08T18:30:30","modified_gmt":"2020-01-08T20:30:30","slug":"valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa","status":"publish","type":"post","link":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/","title":{"rendered":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1337\" src=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2-900x621.jpg\" alt=\"\" width=\"900\" height=\"621\" srcset=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2-900x621.jpg 900w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2-768x530.jpg 768w, http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2.jpg 905w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>O guitarrista Val\u00e9rio Exterminator anuncia que est\u00e1 abrindo a agenda para uma turn\u00ea comemorativa dos 35 anos de cria\u00e7\u00e3o do termo War Metal, firmado em 1985 com a forma\u00e7\u00e3o da banda mineira Holocausto. Em comunicado, o guitarrista declara: <em>\u201cA Cadela raivosa est\u00e1 no cio, e o General da Guerra, a patente mais alta do War Metal, continua na linha de frente. Honrando o estilo criado em 1985, ele apresenta a nova forma\u00e7\u00e3o da banda, e a demo in\u00e9dita dos 35 anos da cria\u00e7\u00e3o do War Metal\u201d. <\/em>O guitarrista ainda comenta: <em>\u201cO ano de 2020 n\u00e3o ser\u00e1 um ano sem o War Metal da banda pioneira do estilo, e jamais ser\u00e1 um ano, em que a agressividade e originalidade da banda, ser\u00e3o jogadas na lama, e transformadas em industrial techno shit.\u201d. <\/em>O m\u00fasico se refere \u00e0 fase experimental do grupo, quando ele esteve afastado. Os discos da \u00e9poca, lan\u00e7ados entre o final da d\u00e9cada de 1980 e in\u00edcio de 1990 flertavam com uma sonoridade extremamente diferente do cl\u00e1ssico <em>\u201cCampo de Exterm\u00ednio\u201d<\/em>, lan\u00e7ado em 1987.<\/p>\n<p>Val\u00e9rio deixa clara sua posi\u00e7\u00e3o: <em>\u201cEu componho Metal Extremo, e tenho muita personalidade e convic\u00e7\u00e3o daquilo que fa\u00e7o. Eu n\u00e3o sigo as tend\u00eancias do Metal, jamais gravarei um disco clonado de VoiV\u00f6d, e em hip\u00f3tese alguma permitirei transformar a agressividade da banda em experimentalismos. Aqui respira-se os horrores da guerra, e seus acontecimentos reais, n\u00e3o fa\u00e7o \u201cTribute a Cicciolina\u201d, apresento letras que trazem \u00e0 tona as atrocidades da nossa ra\u00e7a. Em minhas tropas War Metal n\u00e3o ser\u00e1 mais permitido vocalista que dorme cantando \u201cSc\u00f3ria\u201d e acorda cantando Birlium&#8230;\u201d.<\/em> Para entender o que o guitarrista Val\u00e9rio Exterminator disse sobre <em>&#8220;n\u00e3o ser\u00e1 mais permitido vocalista que dorme cantando \u201cSc\u00f3ria\u201d e acorda cantando Birlium&#8221;<\/em> acesse o link a seguir: <a href=\"https:\/\/www.youtube.com\/watch?v=ylguND5XW8I\">https:\/\/www.youtube.com\/watch?v=ylguND5XW8I<\/a><\/p>\n<p><em>\u201cDi\u00e1rio de Guerra\u201d<\/em>, o \u00faltimo disco do Holocausto com a forma\u00e7\u00e3o cl\u00e1ssica, foi lan\u00e7ado no ano passado pela gravadora americana Nuclear War Now e atrav\u00e9s de dois di\u00e1rios escritos por Val\u00e9rio, no ano passado, os f\u00e3s poder\u00e3o saber mais detalhes sobre o desenrolar da hist\u00f3ria:<\/p>\n<p><strong><em>Leia a primeira parte do di\u00e1rio:<br \/>\n<\/em><\/strong><a href=\"http:\/\/wargodspress.com.br\/wargods\/holocausto-guitarrista-fala-sobre-o-novo-album-diario-de-guerra\/\">http:\/\/wargodspress.com.br\/wargods\/holocausto-guitarrista-fala-sobre-o-novo-album-diario-de-guerra\/<\/a><\/p>\n<p><strong><em>Leia a segunda parte do di\u00e1rio:<br \/>\n<\/em><\/strong><a href=\"http:\/\/wargodspress.com.br\/wargods\/holocausto-confira-a-segunda-parte-do-diario-sobre-o-novo-album\/\">http:\/\/wargodspress.com.br\/wargods\/holocausto-confira-a-segunda-parte-do-diario-sobre-o-novo-album\/<\/a><\/p>\n<p><strong>Contatos:<br \/>\n<\/strong><strong>Facebook: <\/strong><a href=\"http:\/\/www.facebook.com\/ValerioExterminator\">www.facebook.com\/ValerioExterminator<\/a><br \/>\n<strong>E-mail: <\/strong><a href=\"mailto:vallexterminator@gmail.com\">vallexterminator@gmail.com<\/a><br \/>\n<strong>Assessoria de Imprensa: <\/strong><a href=\"http:\/\/www.wargodspress.com.br\">www.wargodspress.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O guitarrista Val\u00e9rio Exterminator anuncia que est\u00e1 abrindo a agenda para uma turn\u00ea comemorativa dos 35 anos de cria\u00e7\u00e3o do<\/p>\n","protected":false},"author":1,"featured_media":1337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[16,17,22],"class_list":["post-1425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-holocausto","tag-valerio-exterminator","tag-wargods-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"og:description\" content=\"O guitarrista Val\u00e9rio Exterminator anuncia que est\u00e1 abrindo a agenda para uma turn\u00ea comemorativa dos 35 anos de cria\u00e7\u00e3o do\" \/>\n<meta property=\"og:url\" content=\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\" \/>\n<meta property=\"og:site_name\" content=\"WARGODS PRESS - 2006 - 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wargodspress\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T20:30:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"905\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WarGodsPress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:site\" content=\"@wargodspress\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"WarGodsPress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\"},\"author\":{\"name\":\"WarGodsPress\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\"},\"headline\":\"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa\",\"datePublished\":\"2020-01-08T20:30:30+00:00\",\"dateModified\":\"2020-01-08T20:30:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"keywords\":[\"Holocausto\",\"Val\u00e9rio Exterminator\",\"Wargods Press\"],\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\",\"name\":\"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026\",\"isPartOf\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\"},\"datePublished\":\"2020-01-08T20:30:30+00:00\",\"dateModified\":\"2020-01-08T20:30:30+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/wargodspress.com.br\/wargods\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#website\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"description\":\"Assessoria e Conte\u00fados\",\"publisher\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#organization\",\"name\":\"WARGODS PRESS - 2006 - 2026\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wargodspress\/\",\"https:\/\/www.facebook.com\/wargodspress\",\"https:\/\/twitter.com\/wargodspress\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"contentUrl\":\"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png\",\"width\":1719,\"height\":635,\"caption\":\"WARGODS PRESS - 2006 - 2026\"},\"image\":{\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2\",\"name\":\"WarGodsPress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g\",\"caption\":\"WarGodsPress\"},\"description\":\"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.\",\"sameAs\":[\"http:\/\/www.wargodspress.com.br\"],\"url\":\"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026","og_description":"O guitarrista Val\u00e9rio Exterminator anuncia que est\u00e1 abrindo a agenda para uma turn\u00ea comemorativa dos 35 anos de cria\u00e7\u00e3o do","og_url":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/","og_site_name":"WARGODS PRESS - 2006 - 2026","article_publisher":"https:\/\/www.facebook.com\/wargodspress","article_published_time":"2020-01-08T20:30:30+00:00","og_image":[{"width":905,"height":624,"url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2019\/11\/Val\u00e9rio-Exterminator-Press2.jpg","type":"image\/jpeg"}],"author":"WarGodsPress","twitter_card":"summary_large_image","twitter_creator":"@wargodspress","twitter_site":"@wargodspress","twitter_misc":{"Escrito por":"WarGodsPress","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#article","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/"},"author":{"name":"WarGodsPress","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2"},"headline":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa","datePublished":"2020-01-08T20:30:30+00:00","dateModified":"2020-01-08T20:30:30+00:00","mainEntityOfPage":{"@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"keywords":["Holocausto","Val\u00e9rio Exterminator","Wargods Press"],"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/","url":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/","name":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa - WARGODS PRESS - 2006 - 2026","isPartOf":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#website"},"datePublished":"2020-01-08T20:30:30+00:00","dateModified":"2020-01-08T20:30:30+00:00","breadcrumb":{"@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/wargodspress.com.br\/wargods\/valerio-exterminator-guitarrista-abre-agenda-para-turne-comemorativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/wargodspress.com.br\/wargods\/"},{"@type":"ListItem","position":2,"name":"Val\u00e9rio Exterminator: Guitarrista abre agenda para turn\u00ea comemorativa"}]},{"@type":"WebSite","@id":"http:\/\/wargodspress.com.br\/wargods\/#website","url":"http:\/\/wargodspress.com.br\/wargods\/","name":"WARGODS PRESS - 2006 - 2026","description":"Assessoria e Conte\u00fados","publisher":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wargodspress.com.br\/wargods\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/wargodspress.com.br\/wargods\/#organization","name":"WARGODS PRESS - 2006 - 2026","url":"http:\/\/wargodspress.com.br\/wargods\/","sameAs":["https:\/\/www.instagram.com\/wargodspress\/","https:\/\/www.facebook.com\/wargodspress","https:\/\/twitter.com\/wargodspress"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/","url":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","contentUrl":"http:\/\/wargodspress.com.br\/wargods\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo-novo-4-2.png","width":1719,"height":635,"caption":"WARGODS PRESS - 2006 - 2026"},"image":{"@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/57390b6095ac3486713a1a3b1421fad2","name":"WarGodsPress","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/wargodspress.com.br\/wargods\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c926860538faceab6faaaec86b7ef70caa691c9added2d15bf6132c40252420?s=96&d=mm&r=g","caption":"WarGodsPress"},"description":"Assessor de Imprensa com a Wargods Press, colaborador da revista Roadie Crew, co-autor do livro T\u00e1 no Sangue! e podcaster com o Metal Legacy.","sameAs":["http:\/\/www.wargodspress.com.br"],"url":"http:\/\/wargodspress.com.br\/wargods\/author\/wargodspress\/"}]}},"_links":{"self":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":1,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"predecessor-version":[{"id":1426,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/posts\/1425\/revisions\/1426"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media\/1337"}],"wp:attachment":[{"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wargodspress.com.br\/wargods\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}